{"id":3388,"date":"2019-10-17T23:24:56","date_gmt":"2019-10-18T09:24:56","guid":{"rendered":"https:\/\/www.service-public.pf\/daie\/?p=3388"},"modified":"2019-10-22T09:30:21","modified_gmt":"2019-10-22T19:30:21","slug":"conf_octa_gestion_oceans_oct2019","status":"publish","type":"post","link":"https:\/\/www.service-public.pf\/daie\/2019\/10\/17\/conf_octa_gestion_oceans_oct2019\/","title":{"rendered":"Conf\u00e9rence de l\u2019OCTA sur la gestion durable des oc\u00e9ans"},"content":{"rendered":"<p><span style=\"color: #000000\">\u00ab\u00a0Le ministre de la Culture et de l\u2019environnement, Heremoana Maamaatuaiahutapu, a particip\u00e9 \u00e0 la conf\u00e9rence de l\u2019OCTA, l\u2019association des pays et territoires d\u2019outre-mer, organis\u00e9e \u00e0 Bruxelles, les 16 et 17 octobre.<\/span><\/p>\n<p><span style=\"color: #000000\">La th\u00e9matique centrale de cette conf\u00e9rence a \u00e9t\u00e9 la gestion durable des oc\u00e9ans. A la fois puissants puits de carbone et r\u00e9servoirs de biodiversit\u00e9, les oc\u00e9ans occupent aujourd\u2019hui une place importante dans les discussions internationales, concernant le changement climatique et l\u2019\u00e9rosion de la biodiversit\u00e9.<\/span><\/p>\n<p><span style=\"color: #000000\"><img decoding=\"async\" class=\"size-medium wp-image-3389 alignleft\" src=\"https:\/\/www.service-public.pf\/daie\/wp-content\/uploads\/sites\/14\/2019\/10\/Ministre-Culture-avec-d\u00e9put\u00e9-europ\u00e9en-St\u00e9phane-Bijoux-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.service-public.pf\/daie\/wp-content\/uploads\/sites\/14\/2019\/10\/Ministre-Culture-avec-d\u00e9put\u00e9-europ\u00e9en-St\u00e9phane-Bijoux-200x150.jpg 200w, https:\/\/www.service-public.pf\/daie\/wp-content\/uploads\/sites\/14\/2019\/10\/Ministre-Culture-avec-d\u00e9put\u00e9-europ\u00e9en-St\u00e9phane-Bijoux-300x225.jpg 300w, https:\/\/www.service-public.pf\/daie\/wp-content\/uploads\/sites\/14\/2019\/10\/Ministre-Culture-avec-d\u00e9put\u00e9-europ\u00e9en-St\u00e9phane-Bijoux-400x300.jpg 400w, https:\/\/www.service-public.pf\/daie\/wp-content\/uploads\/sites\/14\/2019\/10\/Ministre-Culture-avec-d\u00e9put\u00e9-europ\u00e9en-St\u00e9phane-Bijoux-600x450.jpg 600w, https:\/\/www.service-public.pf\/daie\/wp-content\/uploads\/sites\/14\/2019\/10\/Ministre-Culture-avec-d\u00e9put\u00e9-europ\u00e9en-St\u00e9phane-Bijoux-768x576.jpg 768w, https:\/\/www.service-public.pf\/daie\/wp-content\/uploads\/sites\/14\/2019\/10\/Ministre-Culture-avec-d\u00e9put\u00e9-europ\u00e9en-St\u00e9phane-Bijoux-800x600.jpg 800w, https:\/\/www.service-public.pf\/daie\/wp-content\/uploads\/sites\/14\/2019\/10\/Ministre-Culture-avec-d\u00e9put\u00e9-europ\u00e9en-St\u00e9phane-Bijoux-1024x768.jpg 1024w, https:\/\/www.service-public.pf\/daie\/wp-content\/uploads\/sites\/14\/2019\/10\/Ministre-Culture-avec-d\u00e9put\u00e9-europ\u00e9en-St\u00e9phane-Bijoux-1200x900.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/span><span style=\"color: #000000\">L\u2019objet de la rencontre a \u00e9t\u00e9 de partager les points de vue sur la valeur environnementale, \u00e9conomique et sociale des oc\u00e9ans, au travers de projets ou actions phares men\u00e9s par chacun des pays et territoires d\u2019outre-mer (PTOM). La Polyn\u00e9sie fran\u00e7aise a \u00e9t\u00e9 invit\u00e9e \u00e0 intervenir sur 3 sessions de haut niveau pour partager les actions r\u00e9alis\u00e9es, en cours, et les perspectives en faveur des oc\u00e9ans.<\/span><\/p>\n<p><span style=\"color: #000000\">En marge de la conf\u00e9rence, des discussions bilat\u00e9rales se sont tenues avec la Nouvelle-Cal\u00e9donie, concernant des accords de coop\u00e9ration, et avec le d\u00e9put\u00e9 europ\u00e9en St\u00e9phane Bijoux, qui s\u2019est engag\u00e9 \u00e0 d\u00e9fendre les int\u00e9r\u00eats des PTOM fran\u00e7ais aupr\u00e8s de l\u2019Union europ\u00e9enne.<\/span><\/p>\n<p><span style=\"color: #000000\">A l\u2019issue de la conf\u00e9rence, les d\u00e9l\u00e9gations des PTOM se sont accord\u00e9es pour signer une d\u00e9claration sur la gestion durable des oc\u00e9ans et se sont engag\u00e9es \u00e0 renforcer leurs actions respectives en la mati\u00e8re.\u00a0\u00bb<\/span><\/p>\n<p><em>Communiqu\u00e9 de la Pr\u00e9sidence de la Polyn\u00e9sie fran\u00e7aise<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Le ministre de la Culture et de l\u2019environnement, Heremoana Maamaatuaiahutapu, a particip\u00e9 \u00e0 la conf\u00e9rence de l\u2019OCTA, l\u2019association des pays et territoires d\u2019outre-mer, organis\u00e9e \u00e0 Bruxelles, les 16 et 17 octobre. La th\u00e9matique centrale de cette conf\u00e9rence a \u00e9t\u00e9 la gestion durable des oc\u00e9ans. A la fois puissants puits de carbone et r\u00e9servoirs de biodiversit\u00e9,  [&#8230;]<\/p>\n","protected":false},"author":35,"featured_media":3390,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"categories":[2,5],"tags":[],"class_list":["post-3388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-affaires-europeennes"],"_links":{"self":[{"href":"https:\/\/www.service-public.pf\/daie\/wp-json\/wp\/v2\/posts\/3388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.service-public.pf\/daie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.service-public.pf\/daie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/daie\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/daie\/wp-json\/wp\/v2\/comments?post=3388"}],"version-history":[{"count":0,"href":"https:\/\/www.service-public.pf\/daie\/wp-json\/wp\/v2\/posts\/3388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/daie\/wp-json\/wp\/v2\/media\/3390"}],"wp:attachment":[{"href":"https:\/\/www.service-public.pf\/daie\/wp-json\/wp\/v2\/media?parent=3388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.service-public.pf\/daie\/wp-json\/wp\/v2\/categories?post=3388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.service-public.pf\/daie\/wp-json\/wp\/v2\/tags?post=3388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}