{"id":8098,"date":"2016-09-08T08:50:09","date_gmt":"2016-09-08T18:50:09","guid":{"rendered":"http:\/\/www.dgen.pf\/?p=8098"},"modified":"2017-06-06T22:58:36","modified_gmt":"2017-06-07T08:58:36","slug":"concours-de-creation-developpement","status":"publish","type":"post","link":"https:\/\/www.service-public.pf\/dgen\/concours-de-creation-developpement\/","title":{"rendered":"Lancement d&rsquo;un concours de Cr\u00e9ation et D\u00e9veloppement Economique des Entreprises dans le domaine du num\u00e9rique"},"content":{"rendered":"<p>Le gouvernement de la Polyn\u00e9sie fran\u00e7aise, dans le cadre de ses actions en faveur de la relance \u00e9conomique, souhaite renforcer son soutien \u00e0 la cr\u00e9ation et au d\u00e9veloppement d\u2019entreprises dans des secteurs particuli\u00e8rement favorables au d\u00e9veloppement \u00e9conomique. La volont\u00e9 publique est de d\u00e9finir un cadre permettant de stimuler le d\u00e9veloppement de projets s\u2019inscrivant en soutien au d\u00e9veloppement durable du Pays.<\/p>\n<p>Dans ce contexte, le Conseil des Ministres a d\u00e9cid\u00e9 de lancer <strong>trois concours de Cr\u00e9ation et D\u00e9veloppement Economique des Entreprises dans les domaines suivants\u00a0:<\/strong><\/p>\n<ol>\n<li>L\u2019agroalimentaire\u00a0: stimuler la cr\u00e9ation, le d\u00e9veloppement et la mise sur le march\u00e9 de projets \u00e9conomiques et\/ou la r\u00e9alisation d\u2019investissements structurants dans le secteur agroalimentaire tout en soutenant une alimentation s\u00fbre, saine et durable\u00a0;<\/li>\n<li>L\u2019\u00e9conomie circulaire\u00a0: stimuler les m\u00e9thodes de r\u00e9duction de la consommation de mati\u00e8res premi\u00e8res et d\u2019\u00e9nergies en am\u00e9liorant leur utilisation et en promouvant une consommation responsable\u00a0;<\/li>\n<li><strong>Le num\u00e9rique\u00a0: stimuler la cr\u00e9ation, le d\u00e9veloppement et la mise sur le march\u00e9 de projets num\u00e9riques innovants ou d\u2019int\u00e9gration originale au contexte de la Polyn\u00e9sie fran\u00e7aise.<\/strong><\/li>\n<\/ol>\n<p>Le lancement du concours dans le domaine du num\u00e9rique a eu lieu ce jeudi 8 septembre \u00e0 9 heures au Minist\u00e8re de la relance \u00e9conomique. Le jury, plac\u00e9 sous la pr\u00e9sidence du Minist\u00e8re en charge de la relance \u00e9conomique et du num\u00e9rique, sera compos\u00e9 de repr\u00e9sentants de l\u2019administration, de repr\u00e9sentants des professionnels de l\u2019entreprise (MEDEF, CGPME, CCISM, SOFIDEP) et de Tahiti Fa\u2019ahotu. A l\u2019issue du concours,<strong> 6 laur\u00e9ats se verront d\u00e9cerner des prix d\u2019un \u00a0montant s\u2019\u00e9levant entre 500\u00a0000 F CFP et 5\u00a0000\u00a0000 F CFP.<\/strong><\/p>\n<p>Les dossiers de candidature et les r\u00e8glements des concours sont disponibles sur notre site.<br \/>\nLes candidats doivent imp\u00e9rativement s\u2019inscrire <strong>avant le mercredi 26 octobre 2016 \u00e0 midi<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.service-public.pf\/dgen\/wp-content\/uploads\/sites\/3\/2016\/09\/REGLEMENT-Concours-num\u00e9rique-2-1.doc\"><img decoding=\"async\" class=\"alignnone wp-image-8103 size-medium\" src=\"http:\/\/www.dgen.pf\/wp-content\/uploads\/t\u00e9l\u00e9charger-le-r\u00e9glement-300x72.jpg\" alt=\"telecharger-le-reglement\" width=\"300\" height=\"72\" \/><\/a>\u00a0 \u00a0 <a href=\"https:\/\/www.service-public.pf\/dgen\/wp-content\/uploads\/sites\/3\/2016\/09\/Concours-Num\u00e9rique-dossier-type-1-1.docx\"><img decoding=\"async\" class=\"alignnone wp-image-8102 size-medium\" src=\"http:\/\/www.dgen.pf\/wp-content\/uploads\/dossier-type-300x72.jpg\" alt=\"dossier-type\" width=\"300\" height=\"72\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>En cas de difficult\u00e9s ou de questions li\u00e9es au d\u00e9p\u00f4t des dossiers, les points de contact sont :<\/p>\n<p>&#8211; Bernard Costa (<a href=\"mailto:bcosta@tahitifaahotu.pf\">bcosta@tahitifaahotu.pf<\/a>) T\u00e9l.\u00a0: 87 74 02 58<\/p>\n<p>&#8211; Lina Huan (<a href=\"mailto:tahitifaahotu.innovation@gmail.com\">tahitifaahotu.innovation@gmail.com<\/a>) T\u00e9l. : 87 79 33 27<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le gouvernement de la Polyn\u00e9sie fran\u00e7aise, dans le cadre de ses actions en faveur de la relance \u00e9conomique, souhaite renforcer son soutien \u00e0 la cr\u00e9ation et au d\u00e9veloppement d\u2019entreprises dans des secteurs particuli\u00e8rement favorables au d\u00e9veloppement \u00e9conomique. La volont\u00e9 publique est de d\u00e9finir un cadre permettant de stimuler le d\u00e9veloppement de projets s\u2019inscrivant en soutien  [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":8104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[1308],"tags":[277,403,190,57,1296,1307],"class_list":["post-8098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-2","tag-concours","tag-financement","tag-innovation","tag-numerique","tag-projet","tag-tahiti-faahotu"],"_links":{"self":[{"href":"https:\/\/www.service-public.pf\/dgen\/wp-json\/wp\/v2\/posts\/8098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.service-public.pf\/dgen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.service-public.pf\/dgen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dgen\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dgen\/wp-json\/wp\/v2\/comments?post=8098"}],"version-history":[{"count":0,"href":"https:\/\/www.service-public.pf\/dgen\/wp-json\/wp\/v2\/posts\/8098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dgen\/wp-json\/wp\/v2\/media\/8104"}],"wp:attachment":[{"href":"https:\/\/www.service-public.pf\/dgen\/wp-json\/wp\/v2\/media?parent=8098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.service-public.pf\/dgen\/wp-json\/wp\/v2\/categories?post=8098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.service-public.pf\/dgen\/wp-json\/wp\/v2\/tags?post=8098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}