{"id":3493,"date":"2025-03-26T02:37:24","date_gmt":"2025-03-26T01:37:24","guid":{"rendered":"https:\/\/www.service-public.pf\/dicp\/?post_type=avada_faq&#038;p=3493"},"modified":"2025-09-26T04:25:49","modified_gmt":"2025-09-26T02:25:49","slug":"a-quel-moment-est-on-informe-de-la-date-de-reunion-et-de-lavis-rendu-par-la-commission-des-impots","status":"publish","type":"avada_faq","link":"https:\/\/www.service-public.pf\/dicp\/faq-items\/a-quel-moment-est-on-informe-de-la-date-de-reunion-et-de-lavis-rendu-par-la-commission-des-impots\/","title":{"rendered":"A quel moment est-on inform\u00e9 de la date de r\u00e9union et de l\u2019avis rendu par la commission des imp\u00f4ts ?"},"content":{"rendered":"<div class=\"ewa-rteLine\">Vous \u00eates avis\u00e9 au moins 15 jours \u00e0 l\u2019avance de la date de r\u00e9union de la commission. Cet avis est accompagn\u00e9 des r\u00e9ponses et m\u00e9moires de la Direction des imp\u00f4ts et des contributions publiques (DICP) aux courriers de saisine de la commission.<\/div>\n<div class=\"ewa-rteLine\"><\/div>\n<div class=\"ewa-rteLine\">Les parties peuvent compl\u00e9ter l\u2019information de la commission par la production d\u2019un m\u00e9moire en r\u00e9plique adress\u00e9 au pr\u00e9sident de la commission au moins 8 jours avant la r\u00e9union de celle-ci.<\/div>\n<div class=\"ewa-rteLine\"><\/div>\n<div class=\"ewa-rteLine\">La commission vous notifie, ainsi qu\u2019\u00e0 la DICP, son avis dans le d\u00e9lai de 30 jours suivant sa r\u00e9union.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous \u00eates avis\u00e9 au moins 15 jours \u00e0 l\u2019avance de la date de r\u00e9union de la commission. Cet avis est accompagn\u00e9 des r\u00e9ponses et m\u00e9moires de la Direction des imp\u00f4ts et des contributions publiques (DICP) aux courriers de saisine de la commission. Les parties peuvent compl\u00e9ter l\u2019information de la commission par la production d\u2019un m\u00e9moire [&#8230;]<\/p>\n","protected":false},"author":159,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"faq_category":[72],"class_list":["post-3493","avada_faq","type-avada_faq","status-publish","format-standard","hentry","faq_category-commission-des-impots"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/avada_faq\/3493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/avada_faq"}],"about":[{"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/types\/avada_faq"}],"author":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/comments?post=3493"}],"version-history":[{"count":2,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/avada_faq\/3493\/revisions"}],"predecessor-version":[{"id":4842,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/avada_faq\/3493\/revisions\/4842"}],"wp:attachment":[{"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/media?parent=3493"}],"wp:term":[{"taxonomy":"faq_category","embeddable":true,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/faq_category?post=3493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}