{"id":1339,"date":"2023-12-18T22:56:11","date_gmt":"2023-12-18T21:56:11","guid":{"rendered":"https:\/\/www.service-public.pf\/dicp\/?page_id=1339"},"modified":"2024-11-25T02:17:20","modified_gmt":"2024-11-25T01:17:20","slug":"a-propos","status":"publish","type":"page","link":"https:\/\/www.service-public.pf\/dicp\/a-propos\/","title":{"rendered":"A propos"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>La Direction des Imp\u00f4ts et des Contributions Publiques est le service public de l\u2019administration polyn\u00e9sienne charg\u00e9 d\u2019assurer la gestion, le recouvrement et le contr\u00f4le des imp\u00f4ts, droits et taxes directs et indirects pr\u00e9vus au code des imp\u00f4ts et per\u00e7us au profit de la Polyn\u00e9sie fran\u00e7aise, des communes et d\u2019organismes divers. Elle exerce 4 grandes missions\u00a0:<\/p>\n<p><strong>La gestion de l&rsquo;imp\u00f4t<\/strong><\/p>\n<p>La DICP d\u00e9termine la base d\u2019imposition pour une grande partie des imp\u00f4ts per\u00e7us pour le compte du Pays et des communes ainsi que des taxes collect\u00e9es au profit d\u2019organismes divers. A ce titre, elle traite les d\u00e9clarations d\u00e9pos\u00e9es par les contribuables, proc\u00e8de \u00e0 l\u2019\u00e9valuation des bases taxables en cas de d\u00e9faillance d\u00e9clarative et instruit les r\u00e9clamations contentieuses et demandes de remise gracieuse.<\/p>\n<p><strong>Le recouvrement de l&rsquo;imp\u00f4t<\/strong><\/p>\n<p>La DICP assure l\u2019encaissement de la TVA et des imp\u00f4ts directs ou indirects pay\u00e9s sans \u00e9mission d\u2019avis d\u2019imposition (CST, taxe de mise en circulation, \u2026). La DICP met en oeuvre les proc\u00e9dures de recouvrement amiable ou forc\u00e9 \u00e0 l\u2019encontre des reliquataires.<\/p>\n<p><strong>Le contr\u00f4le de l&rsquo;imp\u00f4t<\/strong><\/p>\n<p>Le contr\u00f4le fiscal, contrepartie indispensable du syst\u00e8me d\u00e9claratif, est effectu\u00e9 du bureau (contr\u00f4le sur pi\u00e8ces) et sur place (contr\u00f4le externe). Ce dernier comprend notamment la v\u00e9rification de la comptabilit\u00e9 des entreprises. La DICP assure par ailleurs l\u2019assistance administrative avec les services de l\u2019Etat dans le cadre conventionnel d\u2019\u00e9changes de renseignement.<\/p>\n<p><strong>L&rsquo;\u00e9laboration de la r\u00e9glementation fiscale<\/strong><\/p>\n<p>La DICP con\u00e7oit et \u00e9labore les projets de lois du pays et les arr\u00eat\u00e9s d\u2019application \u00e0 caract\u00e8re fiscal. Elle assure par ailleurs la conception de la doctrine fiscale au travers notamment des instructions administratives publi\u00e9es au bulletin officiel des imp\u00f4ts.<\/p>\n<p>Dans l\u2019exercice quotidien de ses missions, la DICP poursuit les finalit\u00e9s\u00a0:<\/p>\n<ul>\n<li>d\u2019assurer le principe de l\u2019\u00e9galit\u00e9 devant l\u2019imp\u00f4t en promouvant le civisme fiscal,<\/li>\n<li>de garantir la solidarit\u00e9 devant les charges publiques en assurant la surveillance du syst\u00e8me d\u00e9claratif et en luttant contre la fraude,<\/li>\n<li>de favoriser et accro\u00eetre la qualit\u00e9 des services qu\u2019elle rend aux usagers,<\/li>\n<li>de renforcer sa d\u00e9marche de gestion par la performance.<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":137,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-1339","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/pages\/1339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/users\/137"}],"replies":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/comments?post=1339"}],"version-history":[{"count":1,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/pages\/1339\/revisions"}],"predecessor-version":[{"id":1571,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/pages\/1339\/revisions\/1571"}],"wp:attachment":[{"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/media?parent=1339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}