{"id":3187,"date":"2024-12-25T03:35:14","date_gmt":"2024-12-25T02:35:14","guid":{"rendered":"https:\/\/www.service-public.pf\/dicp\/?page_id=3187"},"modified":"2025-08-13T23:27:54","modified_gmt":"2025-08-13T21:27:54","slug":"sinstaller-en-polynesie-francaise","status":"publish","type":"page","link":"https:\/\/www.service-public.pf\/dicp\/autres-situations\/sinstaller-en-polynesie-francaise\/","title":{"rendered":"S&rsquo;installer en polyn\u00e9sie fran\u00e7aise"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Vous envisagez de vous installer en Polyn\u00e9sie fran\u00e7aise, consultez notre FAQ pour mieux pr\u00e9parer votre projet.<\/p>\n<\/div><div class=\"fusion-text fusion-text-2\" style=\"--awb-margin-top:30px;\"><h2 style=\"align-items: center;gap: 10px\"><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27100%27%20height%3D%27100%27%20viewBox%3D%270%200%20100%20100%27%3E%3Crect%20width%3D%27100%27%20height%3D%27100%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.service-public.pf\/dicp\/wp-content\/uploads\/sites\/59\/2024\/12\/DICP_Pictos_Simplification-150x150.jpg\" alt=\"Focus sur\" width=\"100\" height=\"100\" \/><br \/>\nFocus sur&#8230;<\/h2>\n<\/div><style type=\"text\/css\">.fusion-faqs-wrapper #accordian-1 .fusion-panel { border-color:var(--awb-color3); }.fusion-faqs-wrapper #accordian-1 .fusion-panel:hover{ border-color: var(--awb-color3); }.fusion-accordian #accordian-1 .panel-title a .fa-fusion-box:before{ font-size: 16px;width: 16px;}.fusion-accordian #accordian-1 .panel-title a .fa-fusion-box{ color: #ffffff;}.fusion-accordian  #accordian-1 .panel-title a{font-family:var(--awb-typography1-font-family);font-weight:var(--awb-typography1-font-weight);font-style:var(--awb-typography1-font-style);}.fusion-accordian  #accordian-1 .panel-title a:not(:hover){color:var(--awb-color5);}.fusion-accordian  #accordian-1 .toggle-content{font-size:15px;color:var(--awb-color6);font-family:var(--awb-typography4-font-family);font-weight:var(--awb-typography4-font-weight);font-style:var(--awb-typography4-font-style);}.fusion-accordian #accordian-1 .fa-fusion-box { background-color: #0078b5 !important;border-color: #0078b5 !important;}.fusion-accordian #accordian-1 .panel-title a:hover,.fusion-accordian #accordian-1 .panel-title a.hover { color: #001e3c;}.fusion-faq-shortcode .fusion-accordian #accordian-1 .fusion-toggle-boxed-mode:hover .panel-title a { color: #001e3c;}.fusion-accordian #accordian-1 .panel-title a:hover .fa-fusion-box,.fusion-accordian #accordian-1 .panel-title a.hover .fa-fusion-box { background-color: #001e3c!important;border-color: #001e3c!important;}.fusion-faqs-wrapper .fusion-accordian #accordian-1 .panel-title a.active{ color: #001e3c !important;}.fusion-faqs-wrapper .fusion-accordian #accordian-1 .panel-title .active .fa-fusion-box { background-color: #001e3c!important;border-color: #001e3c!important;}<\/style><div class=\"fusion-faq-shortcode\" style=\"\"><div class=\"fusion-faqs-wrapper\"><div class=\"accordian fusion-accordian\"><div class=\"panel-group \" id=\"accordian-1\"><div class=\"fusion-panel panel-default fusion-faq-post fusion-faq-post-3189 installation-polynesie \"><span class=\"entry-title rich-snippet-hidden\">Existe-t-il un imp\u00f4t sur le revenu ?<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/www.service-public.pf\/dicp\/author\/ikva\/\" title=\"Articles par ikva\" rel=\"author\">ikva<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2025-02-28T03:40:56+01:00<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-3189\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-3189\" href=\"#collapse-1-3189\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon fa-arrow-down fas\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon fa-arrow-right fas\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Existe-t-il un imp\u00f4t sur le revenu ?<\/div><\/a><\/h4><\/div><div id=\"collapse-1-3189\" aria-labelledby=\"faq_1-3189\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-3\"><p>Il n\u2019existe pas en Polyn\u00e9sie fran\u00e7aise d\u2019imp\u00f4t g\u00e9n\u00e9ral sur l\u2019ensemble des revenus.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-faq-post fusion-faq-post-3195 installation-polynesie \"><span class=\"entry-title rich-snippet-hidden\">Cr\u00e9er une entreprise<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/www.service-public.pf\/dicp\/author\/ikva\/\" title=\"Articles par ikva\" rel=\"author\">ikva<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2025-02-28T03:41:49+01:00<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-3195\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-3195\" href=\"#collapse-1-3195\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon fa-arrow-down fas\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon fa-arrow-right fas\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Cr\u00e9er une entreprise<\/div><\/a><\/h4><\/div><div id=\"collapse-1-3195\" aria-labelledby=\"faq_1-3195\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-4\"><p>En tant qu\u2019entrepreneur individuel, vous serez soumis \u00e0 la contribution des patentes, \u00e0 la TVA, \u00e0 l\u2019imp\u00f4t sur les transactions et \u00e0 la contribution de solidarit\u00e9 territoriale sur les professions et activit\u00e9s non salari\u00e9es (CST-NS)  ou au r\u00e9gime fiscal des tr\u00e8s petites entreprises.<\/p>\n<p>Si vous cr\u00e9ez une soci\u00e9t\u00e9, vous serez soumis \u00e0 la contribution des patentes, \u00e0 la TVA et \u00e0 l\u2019imp\u00f4t sur les soci\u00e9t\u00e9s.<\/p>\n<p>Pour plus d\u2019information, vous pouvez consulter la rubrique \u00ab Cr\u00e9ation-Cessation \u00bb.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-faq-post fusion-faq-post-3200 installation-polynesie \"><span class=\"entry-title rich-snippet-hidden\">Immatriculer un v\u00e9hicule import\u00e9<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/www.service-public.pf\/dicp\/author\/ikva\/\" title=\"Articles par ikva\" rel=\"author\">ikva<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2025-11-19T02:12:24+01:00<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-3200\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-3200\" href=\"#collapse-1-3200\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon fa-arrow-down fas\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon fa-arrow-right fas\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Immatriculer un v\u00e9hicule import\u00e9<\/div><\/a><\/h4><\/div><div id=\"collapse-1-3200\" aria-labelledby=\"faq_1-3200\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1-3 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-5\"><p>En Polyn\u00e9sie fran\u00e7aise, l\u2019immatriculation du v\u00e9hicule ne peut intervenir qu\u2019au vu d\u2019un justificatif du paiement de la taxe de mise en circulation et de la taxe d\u2019environnement pour le recyclage des v\u00e9hicules d\u00e9livr\u00e9 par la Recette des imp\u00f4ts.<\/p>\n<p>Le paiement de ces deux s\u2019effectue en esp\u00e8ces, par ch\u00e8que certifi\u00e9 de banque ou par virement aupr\u00e8s de la Recette des imp\u00f4ts.<\/p>\n<p>La Recette des imp\u00f4ts peut vous aider \u00e0 calculer le montant de la taxe \u00e0 devoir. Pour nous contacter, vous pouvez :<\/p>\n<ul>\n<li>nous appeler par t\u00e9l\u00e9phone au 40 46 13 13<\/li>\n<li>nous adresser un courrier \u00e0 l\u2019adresse suivante :<\/li>\n<\/ul>\n<p style=\"text-align: center\">Direction des imp\u00f4ts et des contributions publiques (DICP)<\/p>\n<p style=\"text-align: center\">Recette des imp\u00f4ts<\/p>\n<p style=\"text-align: center\">BP 72 \u2013 98713 Papeete<\/p>\n<ul>\n<li>ou vous rendre directement \u00e0 nos guichets d\u2019accueil situ\u00e9s au 1er \u00e9tage du b\u00e2timent administratif, 11 rue du commandant Destremau. R\u00e9ception sans rendez-vous du lundi au vendredi de 7h30 \u00e0 12h30.<\/li>\n<\/ul>\n<p>Il vous faudra cependant fournir les documents suivants :<\/p>\n<ul>\n<li>La feuille de d\u00e9douanement I400 ;<\/li>\n<li>Le certificat servant \u00e0 l\u2019immatriculation d\u00e9livr\u00e9 par les services douaniers ;<\/li>\n<li>La carte grise ou le titre de propri\u00e9t\u00e9. Lorsque ce document n\u2019est pas r\u00e9dig\u00e9 en langue fran\u00e7aise, une traduction effectu\u00e9e par un expert est obligatoire;<\/li>\n<li>La fiche descriptive (notice descriptive) \u00e9tablie par un expert en automobile (non n\u00e9cessaire pour les v\u00e9hicules import\u00e9s de France m\u00e9tropolitaine) ;<\/li>\n<li>Demande de certificat d\u2019immatriculation d\u2019un v\u00e9hicule d\u00fbment rempli (se procurer aupr\u00e8s de la Direction des transports terrestres ou directement sur son site internet : www.transports-terrestres.pf).<\/li>\n<\/ul>\n<p>S&rsquo;agissant des taxes et droits d&rsquo;entr\u00e9e \u00e0 acquitter lors de l&rsquo;importation de votre v\u00e9hicule sur le territoire de la Polyn\u00e9sie fran\u00e7aise, la DICP n&rsquo;est pas le service comp\u00e9tent pour r\u00e9pondre \u00e0 votre demande et vous invite \u00e0 vous rapprocher de la Direction R\u00e9gionale des Douanes de la Polyn\u00e9sie fran\u00e7aise :<\/p>\n<p style=\"text-align: center\">Direction r\u00e9gionale des Douanes de Polyn\u00e9sie fran\u00e7aise<\/p>\n<p style=\"text-align: center\">B.P. 9006 CTC &#8211; 98715 TAHITI<\/p>\n<p style=\"text-align: center\">Standard : (689) 50.55.50 &#8211; Fax : (689) 43.55.45<\/p>\n<p style=\"text-align: center\">Courriel : dr-polynesie@douane.finances.gouv.fr<\/p>\n<p style=\"text-align: center\">Site Internet : www.polynesie-francaise.pref.gouv.fr<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-faq-post fusion-faq-post-3206 installation-polynesie \"><span class=\"entry-title rich-snippet-hidden\">R\u00e9gime fiscal des salaires et pensions de retraite<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/www.service-public.pf\/dicp\/author\/ikva\/\" title=\"Articles par ikva\" rel=\"author\">ikva<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2025-02-28T03:45:33+01:00<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-3206\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-3206\" href=\"#collapse-1-3206\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon fa-arrow-down fas\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon fa-arrow-right fas\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">R\u00e9gime fiscal des salaires et pensions de retraite<\/div><\/a><\/h4><\/div><div id=\"collapse-1-3206\" aria-labelledby=\"faq_1-3206\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1-4 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-6\"><p>D\u00e8s lors que vous \u00eates domicili\u00e9 en Polyn\u00e9sie fran\u00e7aise, le salaire ou le(s) pension(s) de retraites que vous percevez sont soumis \u00e0 la contribution de solidarit\u00e9 territoriale sur les traitements, salaires, pensions, rentes viag\u00e8res et indemnit\u00e9s diverses (CST-S).<\/p>\n<p><a href=\"https:\/\/dev-dicp.pantheonsite.io\/essentiel\/la-contribution-de-solidarite-territoriale-sur-les-traitements-salaires-pensions-rentes\" target=\"_blank\" rel=\"noopener noreferrer\"><u>Cliquez ici pour en savoir d&rsquo;avantage sur la CST-S.<\/u><\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-faq-post fusion-faq-post-3211 installation-polynesie \"><span class=\"entry-title rich-snippet-hidden\">Acqu\u00e9rir une habitation<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/www.service-public.pf\/dicp\/author\/ikva\/\" title=\"Articles par ikva\" rel=\"author\">ikva<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2025-02-28T03:46:43+01:00<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-3211\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-3211\" href=\"#collapse-1-3211\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon fa-arrow-down fas\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon fa-arrow-right fas\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Acqu\u00e9rir une habitation<\/div><\/a><\/h4><\/div><div id=\"collapse-1-3211\" aria-labelledby=\"faq_1-3211\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1-5 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-7\"><p>Vous serez soumis \u00e0 l\u2019imp\u00f4t foncier sur les propri\u00e9t\u00e9s b\u00e2ties.<\/p>\n<p><a href=\"https:\/\/dev-dicp.pantheonsite.io\/essentiel\/limpot-foncier-sur-les-proprietes-baties\" target=\"_blank\" rel=\"noopener noreferrer\"><u>Consultez l&rsquo;essentiel sur cet imp\u00f4t en cliquant ici.<\/u><\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-faq-post fusion-faq-post-3216 installation-polynesie \"><span class=\"entry-title rich-snippet-hidden\">Les conventions fiscales<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/www.service-public.pf\/dicp\/author\/ikva\/\" title=\"Articles par ikva\" rel=\"author\">ikva<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2025-02-28T03:47:50+01:00<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-3216\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-3216\" href=\"#collapse-1-3216\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon fa-arrow-down fas\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon fa-arrow-right fas\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Les conventions fiscales<\/div><\/a><\/h4><\/div><div id=\"collapse-1-3216\" aria-labelledby=\"faq_1-3216\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1-6 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-8\"><p>Seules deux conventions fiscales ont \u00e9t\u00e9 conclues par la Polyn\u00e9sie fran\u00e7aise et uniquement avec la France m\u00e9tropolitaine. Il s\u2019agit de :<\/p>\n<\/p>\n<ul>\n<li>La convention entre le gouvernement fran\u00e7ais et le gouvernement des \u00e9tablissements fran\u00e7ais de l\u2019Oc\u00e9anie de 1957. Consultez l&rsquo;annexe 4 de la 5\u00e8me partie du code ;<\/li>\n<li>L\u2019accord entre l\u2019Etat et la collectivit\u00e9 territoriale de la Polyn\u00e9sie fran\u00e7aise concernant l\u2019assistance administrative mutuelle en mati\u00e8re fiscale (loi organique n\u00b02011-416 du 19 avril 2011).<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-faq-post fusion-faq-post-3781 installation-polynesie \"><span class=\"entry-title rich-snippet-hidden\">Je suis \u00e0 l&rsquo;\u00e9tranger et je souhaite d\u00e9signer un repr\u00e9sentant fiscal<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/www.service-public.pf\/dicp\/author\/ikva\/\" title=\"Articles par ikva\" rel=\"author\">ikva<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2025-03-26T03:40:23+01:00<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-3781\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-3781\" href=\"#collapse-1-3781\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon fa-arrow-down fas\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon fa-arrow-right fas\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Je suis \u00e0 l&rsquo;\u00e9tranger et je souhaite d\u00e9signer un repr\u00e9sentant fiscal<\/div><\/a><\/h4><\/div><div id=\"collapse-1-3781\" aria-labelledby=\"faq_1-3781\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"panel panel-default m-accordion\">\n<div id=\"collapse-1280336832\" class=\"panel-collapse collapse in\" aria-expanded=\"true\">\n<div class=\"panel-body\">\n<p class=\"text-align-justify\">Les modalit\u00e9s de repr\u00e9sentation fiscale en Polyn\u00e9sie fran\u00e7aise sont pr\u00e9vues par l\u2019arr\u00eat\u00e9 n\u00b01132\/CM du 21 juillet 2009.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default fusion-faq-post fusion-faq-post-3785 installation-polynesie \"><span class=\"entry-title rich-snippet-hidden\">Je suis propri\u00e9taire d\u2019une habitation en France, celle-ci est-elle soumise \u00e0 l\u2019imp\u00f4t en Polyn\u00e9sie fran\u00e7aise ?<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/www.service-public.pf\/dicp\/author\/ikva\/\" title=\"Articles par ikva\" rel=\"author\">ikva<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2025-03-26T03:40:55+01:00<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-3785\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-3785\" href=\"#collapse-1-3785\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon fa-arrow-down fas\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon fa-arrow-right fas\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Je suis propri\u00e9taire d\u2019une habitation en France, celle-ci est-elle soumise \u00e0 l\u2019imp\u00f4t en Polyn\u00e9sie fran\u00e7aise ?<\/div><\/a><\/h4><\/div><div id=\"collapse-1-3785\" aria-labelledby=\"faq_1-3785\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"panel panel-default m-accordion\">\n<div id=\"collapse-259909741\" class=\"panel-collapse collapse in\" aria-expanded=\"true\">\n<div class=\"panel-body\">\n<p>Votre habitation sise en France sera soumise \u00e0 la fiscalit\u00e9 de France m\u00e9tropolitaine et ne fera pas l\u2019objet d\u2019une imposition en Polyn\u00e9sie fran\u00e7aise.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":159,"featured_media":0,"parent":3280,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-3187","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/pages\/3187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/comments?post=3187"}],"version-history":[{"count":4,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/pages\/3187\/revisions"}],"predecessor-version":[{"id":4596,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/pages\/3187\/revisions\/4596"}],"up":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/pages\/3280"}],"wp:attachment":[{"href":"https:\/\/www.service-public.pf\/dicp\/wp-json\/wp\/v2\/media?parent=3187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}