{"id":2381,"date":"2018-08-22T16:09:17","date_gmt":"2018-08-23T02:09:17","guid":{"rendered":"https:\/\/www.service-public.pf\/dpam\/?p=2381"},"modified":"2018-08-22T16:09:17","modified_gmt":"2018-08-23T02:09:17","slug":"louragan-lane-menace-hawaii","status":"publish","type":"post","link":"https:\/\/www.service-public.pf\/dpam\/2018\/08\/22\/louragan-lane-menace-hawaii\/","title":{"rendered":"L&rsquo;ouragan LANE menace Hawaii"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:;--awb-padding-right:;--awb-padding-bottom:;--awb-padding-left:;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p>\u00ab\u00a0Les \u00eeles hawa\u00efennes restent vuln\u00e9rables tandis que l&rsquo;ouragan Lane, de cat\u00e9gorie 4, passe au sud de la Grande \u00eele\u00a0\u00bb de Hawaii\u00a0a indiqu\u00e9 le Centre national des ouragans du Pacifique (CHPC), bas\u00e9 \u00e0 Honolulu, dans son bulletin de 18H00 GMT.<\/p>\n<p>Le pr\u00e9sident Donald Trump a invit\u00e9 les habitants \u00e0 se pr\u00e9parer \u00e0 l&rsquo;arriv\u00e9e de cette puissante temp\u00eate, qui s&rsquo;\u00e9tait hiss\u00e9e jusqu&rsquo;\u00e0 la cat\u00e9gorie maximale de 5 sur l&rsquo;\u00e9chelle Saffir-Simpson, avec des vents soufflant \u00e0 260 km\/h. Mercredi matin, ils ont \u00e9t\u00e9 relev\u00e9s \u00e0 250 km\/h.<br \/>\n\u00ab\u00a0Tout le monde sur la trajectoire du #HurricaneLane, s&rsquo;il vous pla\u00eet, pr\u00e9parez-vous, suivez les conseils des responsables de l&rsquo;Etat et locaux\u00a0\u00bb, a tweet\u00e9 M. Trump. \u00ab\u00a0Soyez en s\u00e9curit\u00e9\u00a0\u00bb.<\/p>\n<p><strong>&gt; Les \u00e9coles ferm\u00e9es<\/strong><\/p>\n<p>Toutes les \u00e9coles publiques sont ferm\u00e9es et il est fortement conseill\u00e9 \u00e0 tous les habitants de l&rsquo;archipel de rester chez eux. Les secours sont mobilis\u00e9s et il est demand\u00e9 \u00e0 la population de rep\u00e9rer d\u00e8s \u00e0 pr\u00e9sent la pi\u00e8ce la plus s\u00fbre de leur habitation.<\/p>\n<p>\u200bM\u00eame s&rsquo;il s&rsquo;est un peu essouffl\u00e9, l&rsquo;ouragan reste susceptible de d\u00e9verser des pluies torrentielles sur l&rsquo;archipel (jusqu&rsquo;\u00e0 50 cm) et de provoquer inondations et glissements de terrain.<\/p>\n<p>Ce mercredi \u00e0 11 heures, Lane se rapprochait de l&rsquo;archipel avec des vents atteignant 250 km\/h.\u00a0Lane se d\u00e9place d&rsquo;ouest en nord-ouest et devrait faire un virage progressif vers le nord-ouest ce mercredi, le ramenant \u00ab\u00a0dangereusement pr\u00e8s\u00a0\u00bb des \u00eeles jeudi et jusqu&rsquo;\u00e0 samedi rapporte\u00a0<a href=\"http:\/\/www.hawaiinewsnow.com\/story\/38890702\/hurricane-watch-issued-for-hawaii-maui-counties-as-lane-nears-state\">Hawaii news now<\/a>.<\/p>\n<p>Une \u00ab\u00a0alerte ouragan\u00a0\u00bb est en vigueur \u00e0 Big Island, ainsi pour le comt\u00e9 de Maui, compos\u00e9 de plusieurs \u00eeles, dont celles de Maui, Lanai et une partie de Molokai. Cela signifie que des conditions dignes d&rsquo;un ouragan (vent, pluie, vagues) sont pr\u00e9vues sur ces zones dans les 48 heures.<\/p>\n<p>\u00ab\u00a0L&rsquo;oeil de l&rsquo;ouragan devrait aller tr\u00e8s pr\u00e8s, ou m\u00eame passer au-dessus, des principales \u00eeles de Hawaii entre jeudi et samedi\u00a0\u00bb, selon le service m\u00e9t\u00e9orologique national (NWS), qui s&rsquo;attend \u00e0 ce que les vents se r\u00e9duisent dans les prochains jours, ne les rendant cependant pas moins dangereux.<\/p>\n<p><strong>&gt; Etat d&rsquo;urgence <\/strong><\/p>\n<p>Le gouverneur de l&rsquo;Etat, David Ige, a d\u00e9clar\u00e9 mardi l&rsquo;\u00e9tat d&rsquo;urgence dans une partie du territoire, afin de d\u00e9bloquer des moyens suppl\u00e9mentaires et de fournir de l&rsquo;aide aux \u00e9ventuels sinistr\u00e9s.<br \/>\n<em>\u00ab\u00a0L&rsquo;ouragan Lane n&rsquo;est pas un ouragan sage\u00a0\u00bb<\/em>, a-t-il pr\u00e9venu. \u00ab\u00a0J<em>e n&rsquo;ai jamais vu de modifications aussi importantes des pr\u00e9visions de trajectoire que j&rsquo;en ai vues avec cette temp\u00eate\u00a0\u00bb.<\/em><br \/>\n<em>\u00ab\u00a0J&rsquo;exhorte nos habitants et nos visiteurs \u00e0 prendre cette menace au s\u00e9rieux et \u00e0 se pr\u00e9parer pour un impact d&rsquo;envergure\u00a0\u00bb<\/em>, a-t-il ajout\u00e9.<\/p>\n<p><strong>&gt; Vu de l&rsquo;espace&#8230;<\/strong><\/p>\n<p>Mercredi matin, l&rsquo;astronaute de la NASA Ricky Arnold a twitt\u00e9 deux images de l&rsquo;ouragan Lane vu de l&rsquo;espace. Des images qui montrent la taille impressionnante du ph\u00e9nom\u00e8ne&#8230;<\/p>\n<p><a href=\"https:\/\/t.co\/4mah6UYw7H\">pic.twitter.com\/4mah6UYw7H<\/a><\/p>\n<p>\u2014 Intl. Space Station (@Space_Station) <a href=\"https:\/\/twitter.com\/Space_Station\/status\/1032346616290783238?ref_src=twsrc%5Etfw\">22 ao\u00fbt 2018<\/a><\/p>\n<p>Le coeur des ouragans atteint rarement les terres \u00e0 Hawaii: le dernier ouragan majeur &#8211;au moins cat\u00e9gorie 3&#8211; dont l&rsquo;oeil a touch\u00e9 les terres de l&rsquo;archipel \u00e9tait Iniki, en 1992. Il a caus\u00e9 la mort de six personnes et fait 3 milliards de d\u00e9g\u00e2ts.<\/p>\n<p>Hawaii avait d\u00e9j\u00e0 \u00e9t\u00e9 menac\u00e9 en ao\u00fbt par un ouragan d&rsquo;envergure. <a href=\"https:\/\/www.tntv.pf\/Un-ouragan-se-dirige-vers-Hawaii-un-autre-vers-le-Mexique_a27146.html\">Hector, <\/a>qui a atteint la cat\u00e9gorie 4, est finalement pass\u00e9 bien au large de la grande \u00eele, mais a n\u00e9anmoins provoqu\u00e9 de grosses vagues sur une partie des c\u00f4tes.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:;--awb-padding-right:;--awb-padding-bottom:;--awb-padding-left:;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"732\" height=\"494\" title=\"24804913-26434295\" src=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2018\/08\/24804913-26434295.jpg\" alt class=\"img-responsive wp-image-2380\" srcset=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2018\/08\/24804913-26434295-200x135.jpg 200w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2018\/08\/24804913-26434295-400x270.jpg 400w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2018\/08\/24804913-26434295-600x405.jpg 600w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2018\/08\/24804913-26434295.jpg 732w\" sizes=\"(max-width: 800px) 100vw, 732px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-2\"><p>Photo Copyright Ricky Arnold NASA<\/p>\n<\/div><div class=\"fusion-text fusion-text-3\"><p>Sources info : AFP et TNTV<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":141,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[83],"tags":[],"class_list":["post-2381","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/posts\/2381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/comments?post=2381"}],"version-history":[{"count":0,"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/posts\/2381\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/media?parent=2381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/categories?post=2381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/tags?post=2381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}