{"id":5331,"date":"2019-05-15T15:17:11","date_gmt":"2019-05-16T01:17:11","guid":{"rendered":"https:\/\/www.service-public.pf\/dpam\/?p=5331"},"modified":"2019-05-20T13:47:15","modified_gmt":"2019-05-20T23:47:15","slug":"tahiti-nui-vaa-restrictions-a-la-navigation","status":"publish","type":"post","link":"https:\/\/www.service-public.pf\/dpam\/2019\/05\/15\/tahiti-nui-vaa-restrictions-a-la-navigation\/","title":{"rendered":"Tahiti Nui Va&rsquo;a &#8211; restrictions \u00e0 la navigation"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-first\" style=\"--awb-bg-size:cover;width:50%;width:calc(50% - ( ( 4% ) * 0.5 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p>Chaque grande \u00e9preuve sportive sur l&rsquo;eau n\u00e9cessite des pr\u00e9cautions et des restrictions \u00e0 la navigation afin d&rsquo;assurer une s\u00e9curit\u00e9 maximale aux sportifs et aux spectateurs venus suivre l&rsquo;\u00e9v\u00e8nement. La Tahiti Nui Va&rsquo;a est le prochain grand rendez-vous des rameurs. Cette course se tient tous les deux ans se d\u00e9roule en trois \u00e9tapes autour de l&rsquo;ile de Tahiti. Cette ann\u00e9e elle se tient <strong>les 30, 31 mai et 1<sup>er<\/sup> juin 2019<\/strong>. Longue de 168 kms, elle est r\u00e9put\u00e9e parmi les plus difficiles en raison de sa longueur.<\/p>\n<p>Les \u00e9quipages compos\u00e9s de six rameurs peuvent changer durant les \u00e9tapes\u00a0; cette particularit\u00e9 entraine des conditions de navigations particuli\u00e8res qui imposent prudence et vigilance en raison des va-et-vient des navires qui r\u00e9cup\u00e8rent les rameurs \u00e0 l\u2019eau lors des changements. La s\u00e9curit\u00e9 sur l\u2019eau durant les \u00e9tapes est de la responsabilit\u00e9 de l\u2019organisateur qui doit s\u2019assurer de disposer des moyens n\u00e9cessaires et suffisants. Il lui revient \u00e9galement d\u2019en informer clairement les participants.<\/p>\n<p>Afin de garantir la s\u00e9curit\u00e9 des comp\u00e9titeurs et des spectateurs attendus pour cet \u00e9v\u00e8nement d\u2019envergure, la Direction Polyn\u00e9sienne des Affaires Maritimes (DPAM), en concertation avec l\u2019organisateur, a \u00e9labor\u00e9 un projet d\u2019arr\u00eat\u00e9 relatif aux conditions d\u2019organisation et de d\u00e9roulement de la comp\u00e9tition qui concerne principalement les points d\u2019\u00e9tapes. Cet arr\u00eat\u00e9 adopt\u00e9 lors du conseil des ministres du mercredi 15 mai 2019, pr\u00e9voit l\u2019instauration de 4 zones de r\u00e8glementations sp\u00e9cifiques\u00a0:<\/p>\n<ol>\n<li>\n<h2><strong>La zone 1 (Z1) concerne le d\u00e9part de la 1<sup>\u00e8re<\/sup> \u00e9tape<\/strong> longue de 58 km.<\/h2>\n<\/li>\n<\/ol>\n<p>Le d\u00e9part sera donn\u00e9 dans le bassin de Papeuriri dans la commune de Teva I Uta, commune associ\u00e9e de Mataiea. Cette zone sera restreinte \u00e0 la navigation dans les conditions fix\u00e9es par l\u2019organisateur.<\/p>\n<p>Cette restriction s\u2019appliquera <strong>le jeudi 30 mai 2019 de 7 heures \u00e0 8 heures 30. <span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/Z1-de\u0301part-Mataiea.pdf\">Voir la zone Z1<\/a><\/span><br \/>\n<\/strong><\/p>\n<ol start=\"2\">\n<li>\n<h2><strong>La zone 2 (Z2) concerne l\u2019arriv\u00e9e de la 1<sup>\u00e8re<\/sup> \u00e9tape<\/strong>.<\/h2>\n<\/li>\n<\/ol>\n<p>Elle se situe dans la baie de Tautira sur le lieu d\u00e9nomm\u00e9 le mouillage de Cook. Cette zone sera restreinte \u00e0 la navigation dans les conditions fix\u00e9es par l\u2019organisateur.<\/p>\n<p>Cette restriction s\u2019appliquera <strong>le jeudi 30 mai 2019 de 12 heures \u00e0 13 heures 30<\/strong>. <a href=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/Z2-arrive\u0301e-Tautira.pdf\"><strong><span style=\"color: #0000ff\">Voir la zone Z2<\/span><\/strong><\/a><\/p>\n<ol start=\"3\">\n<li>\n<h2><strong>La zone 3 (Z3) concerne l\u2019arriv\u00e9e de la 2<sup>\u00e8me<\/sup> \u00e9tape<\/strong> longue de 56 km.<\/h2>\n<\/li>\n<\/ol>\n<p>Elle se situe dans la baie de Taunoa. Cette zone sera restreinte \u00e0 la navigation dans les conditions fix\u00e9es par l\u2019organisateur.<\/p>\n<p>Cette restriction s\u2019appliquera <strong>le vendredi 31 mai 2019 de 12 heures \u00e0 13 heures 30<\/strong>. <a href=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/Z3-arrive\u0301e-Pirae.pdf\"><strong><span style=\"color: #0000ff\">Voir la zone Z3<\/span><\/strong><\/a><\/p>\n<ol start=\"4\">\n<li>\n<h2><strong>La zone 4 (Z4) concerne l\u2019arriv\u00e9e de la 3<sup>\u00e8me<\/sup> \u00e9tape<\/strong> longue de 54 km.<\/h2>\n<\/li>\n<\/ol>\n<p>Elle se situe dans le bassin d\u2019Atimaono au lieu dit Pointe Tehoro. Les rameurs franchiront la passe de Rautirare, se dirigeront vers la pointe Oututahia et longeront les c\u00f4tes jusqu\u2019\u00e0 la pointe Tehoro. Entre ces deux lieux, le parcours s\u2019effectuera dans un couloir long de 2700 m\u00e8tres et large de 100 m\u00e8tres qui sera totalement <strong>interdit \u00e0 la circulation des navires<\/strong> immatricul\u00e9s. L\u2019interdiction s\u2019appliquera <strong>le samedi 1<sup>er<\/sup> juin de 13 heures \u00e0 14 heures 30<\/strong>. Seuls les navires identifi\u00e9s comme moyen de surveillance de la manifestation seront autoris\u00e9s \u00e0 p\u00e9n\u00e9trer dans cette zone. <a href=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/Z4-arrive\u0301e-Mataiea.pdf\"><strong><span style=\"color: #0000ff\">Voir la zone Z4<\/span><\/strong><\/a><\/p>\n<p>Les manquements aux r\u00e8gles de limitations d\u2019activit\u00e9s d\u00e9finies par le pr\u00e9sent arr\u00eat\u00e9 sont passibles des peines de contravention de 5<sup>\u00e8me<\/sup> classe pr\u00e9vues par l\u2019article 131-13 du code p\u00e9nal.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-last\" style=\"--awb-bg-size:cover;width:50%;width:calc(50% - ( ( 4% ) * 0.5 ) );\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1280\" height=\"720\" title=\"Conf Presse EDT Va&rsquo;a Image Polyne\u0301sie 1ere\" src=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/conf-presse-EDT-Vaa-image-Polyne\u0301sie-1ere.jpeg\" alt class=\"img-responsive wp-image-5332\" srcset=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/conf-presse-EDT-Vaa-image-Polyne\u0301sie-1ere-200x113.jpeg 200w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/conf-presse-EDT-Vaa-image-Polyne\u0301sie-1ere-400x225.jpeg 400w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/conf-presse-EDT-Vaa-image-Polyne\u0301sie-1ere-600x338.jpeg 600w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/conf-presse-EDT-Vaa-image-Polyne\u0301sie-1ere-800x450.jpeg 800w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/conf-presse-EDT-Vaa-image-Polyne\u0301sie-1ere-1200x675.jpeg 1200w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/conf-presse-EDT-Vaa-image-Polyne\u0301sie-1ere.jpeg 1280w\" sizes=\"(max-width: 800px) 100vw, 600px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-2\"><p>Lors de la conf\u00e9rence de presse, les organisateurs pr\u00e9sentent les nouveaut\u00e9s du parcours. (Image Polyn\u00e9sie 1ere)<\/p>\n<\/div><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"820\" height=\"410\" title=\"Banniere Site Tnv VF 2\" src=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/banniere_site_tnv_VF_2.jpg\" alt class=\"img-responsive wp-image-5333\" srcset=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/banniere_site_tnv_VF_2-200x100.jpg 200w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/banniere_site_tnv_VF_2-400x200.jpg 400w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/banniere_site_tnv_VF_2-600x300.jpg 600w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/banniere_site_tnv_VF_2-800x400.jpg 800w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/banniere_site_tnv_VF_2.jpg 820w\" sizes=\"(max-width: 800px) 100vw, 600px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-3\"><p>Image de Une : l&rsquo;\u00e9quipage d&rsquo;EDT Va&rsquo;a, club de l&rsquo;entreprise organisatrice de l&rsquo;\u00e9v\u00e8nement. Image D\u00e9p\u00eache de Tahiti.<\/p>\n<\/div><div class=\"fusion-button-wrapper fusion-aligncenter\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/AT-N\u00b0723.CM-du-16.05.2019.pdf\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Consulter l&rsquo;arr\u00eat\u00e9 n\u00b0723 CM du 16 mai 2019<\/span><\/a><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><img decoding=\"async\" width=\"1341\" height=\"947\" title=\"Programme TNV 2019\" src=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/Programme-TNV-2019.png\" alt class=\"img-responsive wp-image-5347\" srcset=\"https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/Programme-TNV-2019-200x141.png 200w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/Programme-TNV-2019-400x282.png 400w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/Programme-TNV-2019-600x424.png 600w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/Programme-TNV-2019-800x565.png 800w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/Programme-TNV-2019-1200x847.png 1200w, https:\/\/www.service-public.pf\/dpam\/wp-content\/uploads\/sites\/20\/2019\/05\/Programme-TNV-2019.png 1341w\" sizes=\"(max-width: 800px) 100vw, 1200px\" \/><\/span><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":141,"featured_media":5334,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[129,14],"tags":[],"class_list":["post-5331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-communiques-de-presse"],"_links":{"self":[{"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/posts\/5331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/comments?post=5331"}],"version-history":[{"count":1,"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/posts\/5331\/revisions"}],"predecessor-version":[{"id":20225,"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/posts\/5331\/revisions\/20225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/media\/5334"}],"wp:attachment":[{"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/media?parent=5331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/categories?post=5331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.service-public.pf\/dpam\/wp-json\/wp\/v2\/tags?post=5331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}