{"id":24836,"date":"2021-08-31T16:30:12","date_gmt":"2021-09-01T02:30:12","guid":{"rendered":"https:\/\/www.service-public.pf\/dsp\/?page_id=24836"},"modified":"2023-07-31T10:56:57","modified_gmt":"2023-07-31T20:56:57","slug":"faq-vaccination","status":"publish","type":"page","link":"https:\/\/www.service-public.pf\/dsp\/covid-19-3\/faq-vaccination\/","title":{"rendered":"FAQ Vaccination COVID-19"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns img-carrousel\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-overflow:visible;--awb-padding-top:0px;--awb-padding-right:0px;--awb-padding-bottom:0px;--awb-padding-left:0px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-no-large-visibility\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-right:0px;--awb-padding-bottom:0px;--awb-padding-left:0px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:3%;--awb-padding-right:0%;--awb-padding-left:10%;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_2_3 2_3 fusion-two-third fusion-column-first\" style=\"--awb-bg-size:cover;width:66.666666666667%;width:calc(66.666666666667% - ( ( 4% ) * 0.66666666666667 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-one\" style=\"--awb-text-color:#ffffff;--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;--awb-font-size:40px;\" id=\"titre-conteneur\"><h1 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:40;line-height:1.4;\">FAQ VACCINATION COVID-19<\/h1><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:20px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-1\"><h2 style=\"text-align: center\" data-fontsize=\"28\" data-lineheight=\"42\">INFORMATIONS G\u00c9N\u00c9RALES<\/h2>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-top:-2%;margin-bottom:3%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#c53466;border-color:#c53466;border-top-width:7px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:25px;--awb-padding-right:10px;--awb-padding-bottom:25px;--awb-padding-left:10px;--awb-bg-color:rgba(237,237,237,0.5);--awb-bg-color-hover:rgba(237,237,237,0.5);--awb-bg-blend:screen;--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:2px;--awb-icon-size:18px;--awb-content-font-size:18px;--awb-icon-alignment:right;--awb-hover-color:#f9f9f9;--awb-border-color:#c53466;--awb-background-color:#ffffff;--awb-divider-color:#e0dede;--awb-divider-hover-color:#e0dede;--awb-icon-color:#c53466;--awb-title-color:#1d9bac;--awb-content-color:#4a4e57;--awb-icon-box-color:#333333;--awb-toggle-hover-accent-color:#000000;--awb-title-font-family:&quot;Roboto&quot;;--awb-title-font-weight:400;--awb-title-font-style:normal;--awb-content-font-family:&quot;Roboto&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;\"><div class=\"panel-group fusion-toggle-icon-right fusion-toggle-icon-unboxed\" id=\"accordion-24836-1\"><div class=\"fusion-panel panel-default panel-06a55f4aadc158f72 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_06a55f4aadc158f72\"><a aria-expanded=\"false\" aria-controls=\"06a55f4aadc158f72\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#06a55f4aadc158f72\" href=\"#06a55f4aadc158f72\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Qu'est-ce qu'un vaccin et la vaccination ?<\/span><\/a><\/h4><\/div><div id=\"06a55f4aadc158f72\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_06a55f4aadc158f72\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Les vaccins sont des <strong>m\u00e9dicaments inject\u00e9s \u00e0 des personnes non malades pour stimuler leur syst\u00e8me immunitaire et les prot\u00e9ger contre une maladie.<\/strong> Ils sont compos\u00e9s de microbes tu\u00e9 (virus ou bact\u00e9ries) ou de fragments de microbes appel\u00e9s \u00ab antig\u00e8nes \u00bb, que le syst\u00e8me immunitaire va d\u00e9tecter comme \u00ab intrus \u00bb et chercher \u00e0 \u00e9liminer. Lors de la vaccination, le syst\u00e8me immunitaire apprend \u00e0 reconnaitre l\u2019antig\u00e8ne \u00e9tranger et produit des anticorps sp\u00e9cifiques contre cet antig\u00e8ne. Par la suite, lorsque le vrai microbe p\u00e9n\u00e8tre dans l\u2019organisme, il est imm\u00e9diatement reconnu et neutralis\u00e9 par les anticorps, la maladie ne se d\u00e9veloppe pas.<\/p>\n<p><strong>Se faire vacciner c\u2019est se prot\u00e9ger soi contre des maladies dont les complications peuvent \u00eatre graves voire mortelles mais c\u2019est aussi prot\u00e9ger les autres. En \u00e9vitant la maladie, on diminue le risque de contaminer les autres.<\/strong><\/p>\n<p>Lorsque qu\u2019une part importante de la population est vaccin\u00e9e, on parle d\u2019<strong>immunit\u00e9 collective ou de groupe<\/strong>. Les personnes vaccin\u00e9es, en ne participant pas \u00e0 la propagation du virus, emp\u00eachent celui-ci de circuler, ce qui permet de prot\u00e9ger aussi ceux qui ne peuvent pas \u00eatre vaccin\u00e9s ou qui sont moins bien prot\u00e9g\u00e9s par les vaccins.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-3e58ea3de10599238 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_3e58ea3de10599238\"><a aria-expanded=\"false\" aria-controls=\"3e58ea3de10599238\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#3e58ea3de10599238\" href=\"#3e58ea3de10599238\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi me faire vacciner contre la COVID-19 ?<\/span><\/a><\/h4><\/div><div id=\"3e58ea3de10599238\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_3e58ea3de10599238\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>La vaccination contre la Covid-19 est efficace \u00e0 plus de 90% contre le risque de survenue de formes graves de la maladie. Elle permet d\u2019\u00e9viter de d\u00e9velopper des sympt\u00f4mes importants qui pourraient n\u00e9cessiter une hospitalisation voire une r\u00e9animation.<\/p>\n<p><b>Des premiers r\u00e9sultats d&rsquo;\u00e9tudes en cours permettent aussi de dire que les vaccins dont nous disposons permettent de diminuer la transmission du virus \u00e0 d&rsquo;autres personnes (nous sommes moins voire non contagieux pour les autres). Par cons\u00e9quent, en nous vaccinant, nous nous prot\u00e9geons de la maladie mais aussi les autres, en ne leur transmettant pas le virus.\u00a0<\/b><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-45df67aaf4ce61f23 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_45df67aaf4ce61f23\"><a aria-expanded=\"false\" aria-controls=\"45df67aaf4ce61f23\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#45df67aaf4ce61f23\" href=\"#45df67aaf4ce61f23\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00c0 quoi \u00e7a sert de se faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"45df67aaf4ce61f23\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_45df67aaf4ce61f23\"><div class=\"panel-body toggle-content fusion-clearfix\"><span style=\"font-weight: 400\">Se faire vacciner c\u2019est se prote\u0301ger contre la maladie et les complications qui peuvent e\u0302tre graves, voire mortelles.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La vaccination permet aussi de prot\u00e9ger les autres en diminuant le risque de les contaminer.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Toutes les personnes vaccine\u0301es empe\u0302chent la circulation du virus et prote\u0300ge ainsi ceux qui ne peuvent pas e\u0302tre vaccine\u0301s ou qui sont moins bien prote\u0301ge\u0301s par le vaccin (personnes \u00e2g\u00e9es, personnes avec des longues maladies, etc)<\/span><\/p>\n<p><span style=\"font-weight: 400\">Lorsqu&rsquo;une part importante de la population est vaccine\u0301e, on parle d\u2019immunite\u0301 collective (ou de groupe).<\/span><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-eaadc89b4f5bf8e30 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_eaadc89b4f5bf8e30\"><a aria-expanded=\"false\" aria-controls=\"eaadc89b4f5bf8e30\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#eaadc89b4f5bf8e30\" href=\"#eaadc89b4f5bf8e30\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est ce que le vaccin est gratuit ?<\/span><\/a><\/h4><\/div><div id=\"eaadc89b4f5bf8e30\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_eaadc89b4f5bf8e30\"><div class=\"panel-body toggle-content fusion-clearfix\"><span style=\"font-weight: 400\">OUI ! La vaccination est gratuite depuis son lancement en Polyn\u00e9sie fran\u00e7aise en janvier 2021.<\/span><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-5aff2d82e44a65273 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_5aff2d82e44a65273\"><a aria-expanded=\"false\" aria-controls=\"5aff2d82e44a65273\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#5aff2d82e44a65273\" href=\"#5aff2d82e44a65273\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">O\u00f9 sont situ\u00e9s les centres de vaccination ?<\/span><\/a><\/h4><\/div><div id=\"5aff2d82e44a65273\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_5aff2d82e44a65273\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Les centres de vaccination sont d\u00e9ploy\u00e9s sur Tahiti, Moorea et dans les \u00eeles \u00e9loign\u00e9es<\/span><\/p>\n<p><span style=\"font-weight: 400\">La liste compl\u00e8te est disponible sur le site internet de la Direction de la sant\u00e9 :\u00a0<\/span><a href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/vaccination-covid\/\"><span style=\"font-weight: 400\">https:\/\/www.service-public.pf\/dsp\/covid-19\/vaccination-covid\/<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400\">Des vaccinodromes sont \u00e9galement organis\u00e9s r\u00e9guli\u00e8rement dans certaines communes.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-6cff9274479514256 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6cff9274479514256\"><a aria-expanded=\"false\" aria-controls=\"6cff9274479514256\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#6cff9274479514256\" href=\"#6cff9274479514256\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est-ce que les vaccinodromes proposent les deux vaccins ?<\/span><\/a><\/h4><\/div><div id=\"6cff9274479514256\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_6cff9274479514256\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">OUI ! Tous les vaccinodromes d\u00e9ploy\u00e9s proposent les deux vaccins.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-6e65cec579c661392 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6e65cec579c661392\"><a aria-expanded=\"false\" aria-controls=\"6e65cec579c661392\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#6e65cec579c661392\" href=\"#6e65cec579c661392\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est-ce que les centres de vaccination proposent les deux vaccins ?<\/span><\/a><\/h4><\/div><div id=\"6e65cec579c661392\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_6e65cec579c661392\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">NON ! Pour des raisons de logistique, tous les centres ne peuvent pas proposer les deux vaccins.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-ead35c6536939b4f2 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_ead35c6536939b4f2\"><a aria-expanded=\"false\" aria-controls=\"ead35c6536939b4f2\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#ead35c6536939b4f2\" href=\"#ead35c6536939b4f2\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Comment faire pour avoir son QR Code ?<\/span><\/a><\/h4><\/div><div id=\"ead35c6536939b4f2\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_ead35c6536939b4f2\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Vous devez d\u2019abord avoir un schema vaccinal complet (voir ici <\/span><a href=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/08\/2021-08-12-schemas-vaccinaux.pdf\"><span style=\"font-weight: 400\">https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/08\/2021-08-12-schemas-vaccinaux.pdf<\/span><\/a><span style=\"font-weight: 400\">)\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Vous pouvez ensuite faire une demande en ligne via ce formulaire : <\/span><a href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/demande-certificat-vaccination\/\"><span style=\"font-weight: 400\">https:\/\/www.service-public.pf\/dsp\/covid-19\/demande-certificat-vaccination\/<\/span><\/a> <\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-dab1c3a37c4e0cae8 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_dab1c3a37c4e0cae8\"><a aria-expanded=\"false\" aria-controls=\"dab1c3a37c4e0cae8\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#dab1c3a37c4e0cae8\" href=\"#dab1c3a37c4e0cae8\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Une personne vaccin\u00e9e peut-\u00eatre porteuse du virus ?<\/span><\/a><\/h4><\/div><div id=\"dab1c3a37c4e0cae8\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_dab1c3a37c4e0cae8\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Oui\u00a0! Cependant la vaccination va lui permettre de se prot\u00e9ger et d\u2019\u00e9viter de d\u00e9velopper la maladie avec des sympt\u00f4mes graves.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-e6028ab2cf2b9f540 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_e6028ab2cf2b9f540\"><a aria-expanded=\"false\" aria-controls=\"e6028ab2cf2b9f540\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#e6028ab2cf2b9f540\" href=\"#e6028ab2cf2b9f540\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Une personne vaccin\u00e9e peut-\u00eatre contagieuse ?<\/span><\/a><\/h4><\/div><div id=\"e6028ab2cf2b9f540\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_e6028ab2cf2b9f540\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Oui\u00a0! Cependant la vaccin<\/span><span style=\"font-weight: 400\">ation peut r\u00e9duire sa charge virale et donc r\u00e9duire ses risques d\u2019\u00eatre contagieuse ou de contaminer son entourage.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-b579c6c9be56ad770 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_b579c6c9be56ad770\"><a aria-expanded=\"false\" aria-controls=\"b579c6c9be56ad770\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#b579c6c9be56ad770\" href=\"#b579c6c9be56ad770\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Une personne vaccin\u00e9e peut-\u00eatre positive ?<\/span><\/a><\/h4><\/div><div id=\"b579c6c9be56ad770\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_b579c6c9be56ad770\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Oui\u00a0! Mais la vaccination diminue fortement le risque de d\u00e9velopper une forme grave de la maladie, d\u2019avoir des sympt\u00f4mes graves.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-dfb6cf63bf212c676 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_dfb6cf63bf212c676\"><a aria-expanded=\"false\" aria-controls=\"dfb6cf63bf212c676\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#dfb6cf63bf212c676\" href=\"#dfb6cf63bf212c676\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi une personne vaccin\u00e9e peut tomber malade ou finir \u00e0 l\u2019h\u00f4pital ?<\/span><\/a><\/h4><\/div><div id=\"dfb6cf63bf212c676\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_dfb6cf63bf212c676\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">I<\/span><span style=\"font-weight: 400\">l n&rsquo;y a pas d&rsquo;efficacit\u00e9 \u00e0 100 %, et chacun peut r\u00e9agir diff\u00e9remment \u00e0 la vaccination comme \u00e0 la maladie. Une personne particuli\u00e8rement fragile (maladies pr\u00e9existantes, comorbidit\u00e9s, \u00e2ge) peut faire une forme grave malgr\u00e9 la vaccination.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Dans la plupart des cas les gens vaccin\u00e9s sont prot\u00e9g\u00e9s des formes graves.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-8ce6f6604a0364ae8 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_8ce6f6604a0364ae8\"><a aria-expanded=\"false\" aria-controls=\"8ce6f6604a0364ae8\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#8ce6f6604a0364ae8\" href=\"#8ce6f6604a0364ae8\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi une personne vaccin\u00e9e, pouvant transmettre le virus, n\u2019a pas de test RT-PCR impos\u00e9 pour aller dans les \u00eeles ?<\/span><\/a><\/h4><\/div><div id=\"8ce6f6604a0364ae8\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_8ce6f6604a0364ae8\"><div class=\"panel-body toggle-content fusion-clearfix\"><span style=\"font-weight: 400\">Car une personne vaccin\u00e9e r\u00e9duit sa charge virale en \u00e9tant vaccin\u00e9e et donc r\u00e9duit ses risques d\u2019\u00eatre contagieuse ou de contaminer son entourage.<\/span><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-3afa865e36676c050 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_3afa865e36676c050\"><a aria-expanded=\"false\" aria-controls=\"3afa865e36676c050\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#3afa865e36676c050\" href=\"#3afa865e36676c050\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi est-ce que l\u2019on vaccine en p\u00e9riode d\u2019\u00e9pid\u00e9mie alors que normalement il ne faut pas le faire ?<\/span><\/a><\/h4><\/div><div id=\"3afa865e36676c050\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_3afa865e36676c050\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Nous pouvons tout \u00e0 fait vacciner en p\u00e9riode d&rsquo;\u00e9pid\u00e9mie lorsqu&rsquo;il y a \u00ab\u00a0urgence\u00a0\u00bb\u00a0 \u00e0 le faire. Nous sommes en situation d\u2019urgence.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-52f6c89ac8bbe8bfc fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_52f6c89ac8bbe8bfc\"><a aria-expanded=\"false\" aria-controls=\"52f6c89ac8bbe8bfc\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#52f6c89ac8bbe8bfc\" href=\"#52f6c89ac8bbe8bfc\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Les vaccins Covid-19 conf\u00e8rent-ils une immunit\u00e9 de groupe ou protection collective ?<\/span><\/a><\/h4><\/div><div id=\"52f6c89ac8bbe8bfc\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_52f6c89ac8bbe8bfc\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div id=\"b6bb230bf9b6785d2\" class=\"panel-collapse collapse in\"><strong>OUI.<\/strong> Au moins pour les vaccins ARNm que nous utilisons actuellement, les r\u00e9sultats d&rsquo;\u00e9tudes montrent une diminution de 80 \u00e0 90% du portage du virus (on a le virus, mais on n&rsquo;est pas malade). Autrement dit, nous sommes moins contagieux et le risque de transmettre le virus \u00e0 une autre personne est faible.<\/div>\n<div><\/div>\n<div class=\"panel-collapse collapse in\">Il est fortement probable que les vaccins exercent un effet de groupe si les taux de couverture vaccinale sont suffisants, c&rsquo;est-\u00e0-dire que plus nous sommes vaccin\u00e9s moins le virus peut \u00eatre transmis et donc le virus ne peux plus circuler dans la population.<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-5e9379b2c0114b331 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_5e9379b2c0114b331\"><a aria-expanded=\"false\" aria-controls=\"5e9379b2c0114b331\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#5e9379b2c0114b331\" href=\"#5e9379b2c0114b331\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi on ne rend pas la vaccination obligatoire ?<\/span><\/a><\/h4><\/div><div id=\"5e9379b2c0114b331\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_5e9379b2c0114b331\"><div class=\"panel-body toggle-content fusion-clearfix\"><span style=\"font-weight: 400\">La vaccination est non obligatoire depuis son lancement en Polyn\u00e9sie fran\u00e7aise en janvier 2021. Cependant, une loi de Pays a \u00e9t\u00e9 vot\u00e9e (N\u00b02021-37) le 23 aout 2021 relative \u00e0 l\u2019obligation de vaccination de certaines cat\u00e9gories de personn<\/span><span style=\"font-weight: 400\">es.<\/span><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-e790b84428a186b65 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_e790b84428a186b65\"><a aria-expanded=\"false\" aria-controls=\"e790b84428a186b65\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#e790b84428a186b65\" href=\"#e790b84428a186b65\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi vaccine t-on les personnes en bonne sant\u00e9 et les enfants ?<\/span><\/a><\/h4><\/div><div id=\"e790b84428a186b65\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_e790b84428a186b65\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Pour limiter la circulation du virus et prot\u00e9ger la collectivit\u00e9 (leur famille entre-autres) et pour limiter le nombre de formes graves et les arr\u00eats de travail afin de pr\u00e9server l&rsquo;\u00e9conomie du pays.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-4afa170f9d8575330 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_4afa170f9d8575330\"><a aria-expanded=\"false\" aria-controls=\"4afa170f9d8575330\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#4afa170f9d8575330\" href=\"#4afa170f9d8575330\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quel est l'impact positif de la vaccination de masse actuelle sur les hospitalisations, sur la r\u00e9animation, et malheureusement sur le nombre de morts ?<\/span><\/a><\/h4><\/div><div id=\"4afa170f9d8575330\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_4afa170f9d8575330\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Sur un million de non vaccin\u00e9s, 132 personnes sont hospitalis\u00e9es et 35 admises en r\u00e9animation. Sur un million de personnes partiellement vaccin\u00e9es, 37 sont hospitalis\u00e9es et huit en r\u00e9animation. Sur un million de personnes compl\u00e8tement vaccin\u00e9es, 16 sont hospitalis\u00e9es et quatre en r\u00e9animation. Conclusion : le vaccin des formes graves.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Voir graphe :<\/span><\/p>\n<div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><a href=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-1024x754.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[6d19bebd7734bf63131]\" data-title=\"Admissions Medicales\" title=\"Admissions Medicales\"><img decoding=\"async\" width=\"600\" height=\"442\" src=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-600x442.jpg\" alt class=\"img-responsive wp-image-25069\" srcset=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-200x147.jpg 200w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-400x295.jpg 400w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-600x442.jpg 600w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-800x589.jpg 800w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-1200x884.jpg 1200w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales.jpg 1280w\" sizes=\"(max-width: 1100px) 100vw, 1200px\" \/><\/a><\/span><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-a80d3d6c53f6a2a8e fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_a80d3d6c53f6a2a8e\"><a aria-expanded=\"false\" aria-controls=\"a80d3d6c53f6a2a8e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-1\" data-target=\"#a80d3d6c53f6a2a8e\" href=\"#a80d3d6c53f6a2a8e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi il n\u2019y a pas de PFIZER dans les Tuamotu ?<\/span><\/a><\/h4><\/div><div id=\"a80d3d6c53f6a2a8e\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_a80d3d6c53f6a2a8e\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Le vaccin PFIZER doit \u00eatre conserv\u00e9 dans des conditions plus compliqu\u00e9es que le vaccin JANSSEN (tr\u00e8s haute temp\u00e9rature, d\u00e9lais de conservation court, etc.)<\/span><\/p>\n<p><span style=\"font-weight: 400\">De plus, le vaccin PFIZER n\u00e9cessite 2 doses, il est donc n\u00e9cessaire de faire d\u00e9placer les \u00e9quipes et la logistique deux fois.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le\u00a0vaccin JANSSEN\u00a0est plus facile \u00e0 conserver et \u00e0 utiliser.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Pour autant ces deux vaccins sont tr\u00e8s efficace pour se prot\u00e9ger de la covid-19.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-2\"><h2 style=\"text-align: center\" data-fontsize=\"28\" data-lineheight=\"42\">PERSONNES CONCERN\u00c9ES<\/h2>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-top:-2%;margin-bottom:3%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#c53466;border-color:#c53466;border-top-width:7px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-1 fusion_builder_column_inner_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:25px;--awb-padding-right:10px;--awb-padding-bottom:25px;--awb-padding-left:10px;--awb-bg-color:rgba(237,237,237,0.5);--awb-bg-color-hover:rgba(237,237,237,0.5);--awb-bg-blend:screen;--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:2px;--awb-icon-size:18px;--awb-content-font-size:18px;--awb-icon-alignment:right;--awb-hover-color:#f9f9f9;--awb-border-color:#c53466;--awb-background-color:#ffffff;--awb-divider-color:#e0dede;--awb-divider-hover-color:#e0dede;--awb-icon-color:#c53466;--awb-title-color:#1d9bac;--awb-content-color:#4a4e57;--awb-icon-box-color:#333333;--awb-toggle-hover-accent-color:#000000;--awb-title-font-family:&quot;Roboto&quot;;--awb-title-font-weight:400;--awb-title-font-style:normal;--awb-content-font-family:&quot;Roboto&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;\"><div class=\"panel-group fusion-toggle-icon-right fusion-toggle-icon-unboxed\" id=\"accordion-24836-2\"><div class=\"fusion-panel panel-default panel-4c0dd7ee0dd0e0300 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_4c0dd7ee0dd0e0300\"><a aria-expanded=\"false\" aria-controls=\"4c0dd7ee0dd0e0300\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-2\" data-target=\"#4c0dd7ee0dd0e0300\" href=\"#4c0dd7ee0dd0e0300\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Je suis sujet contact d\u2019un cas confirm\u00e9 de covid-19, puis-je me faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"4c0dd7ee0dd0e0300\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_4c0dd7ee0dd0e0300\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div id=\"b08d42b7099059490\" class=\"panel-collapse collapse in\">\n<div class=\"panel-body toggle-content fusion-clearfix\">Pas dans l\u2019imm\u00e9diat. Je dois avant tout m\u2019isoler pendant 10 jours apr\u00e8s le dernier contact avec le cas positif. Si je ne d\u00e9veloppe pas de sympt\u00f4me durant cette p\u00e9riode, je dois r\u00e9aliser un test PCR de contr\u00f4le avant ma sortie d\u2019isolement. S\u2019il est n\u00e9gatif, je peux alors aller me faire vacciner.<\/div>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-ac39a47168c45a37c fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_ac39a47168c45a37c\"><a aria-expanded=\"false\" aria-controls=\"ac39a47168c45a37c\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-2\" data-target=\"#ac39a47168c45a37c\" href=\"#ac39a47168c45a37c\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">J\u2019ai d\u00e9j\u00e0 eu la Covid-19 ou je crois l\u2019avoir eue, puis-je me faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"ac39a47168c45a37c\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_ac39a47168c45a37c\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div id=\"b6bb230bf9b6785d2\" class=\"panel-collapse collapse in\">\n<p><strong>Oui, c&rsquo;est possible apr\u00e8s un d\u00e9lai de 2 mois suite \u00e0 mon infection.<\/strong> En r\u00e8gle g\u00e9n\u00e9rale, il n\u2019y a aucune contre-indication \u00e0 vacciner quelqu\u2019un contre une maladie qu\u2019il a d\u00e9j\u00e0 eue.<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-a82978dcb553af3d7 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_a82978dcb553af3d7\"><a aria-expanded=\"false\" aria-controls=\"a82978dcb553af3d7\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-2\" data-target=\"#a82978dcb553af3d7\" href=\"#a82978dcb553af3d7\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00c0 partir de quel \u00e2ge peut-on se faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"a82978dcb553af3d7\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_a82978dcb553af3d7\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">\u00c0 partir de l\u2019\u00e2ge de 12 ans avec le vaccin PFIZER et \u00e0 partir de l\u2019\u00e2ge de 18 ans pour le vaccin JANSSEN.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Un\u00a0mineur de 12 \u00e0 15 ans inclus dois venir avec une autorisation e\u0301crite d\u2019un des deux parents ou d\u2019un tuteur le\u0301gal.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Un\u00a0mineur de 16 \u00e0 17 ans inclus\u00a0peux se faire vacciner sans autorisation parentale. La pre\u0301sence de ses parents ou d\u2019un tuteur le\u0301gal est recommande\u0301e mais n\u2019est plus obligatoire.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-cb12afcdab53617f6 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_cb12afcdab53617f6\"><a aria-expanded=\"false\" aria-controls=\"cb12afcdab53617f6\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-2\" data-target=\"#cb12afcdab53617f6\" href=\"#cb12afcdab53617f6\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi on ne vaccine pas les enfants de moins de 12 ans ?<\/span><\/a><\/h4><\/div><div id=\"cb12afcdab53617f6\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_cb12afcdab53617f6\"><div class=\"panel-body toggle-content fusion-clearfix\"><b>Le vaccin Pfizer permet de vacciner les adolescents \u00e0 partir de 12 ans car il a \u00e9t\u00e9 \u00e9valu\u00e9 \u00e0 partir de cet \u00e2ge.<\/b><\/p>\n<p>Le vaccin Janssen permet de vacciner les personnes \u00e0 partir de 18 ans car il a \u00e9t\u00e9 \u00e9valu\u00e9 \u00e0 partir de cet \u00e2ge. Pour les personnes en dessous de 18 ans, les \u00e9tudes sont encore en cours d\u2019\u00e9valuation de l\u2019efficacit\u00e9 du vaccin.<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-5d3bdfebbe5f528cc fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_5d3bdfebbe5f528cc\"><a aria-expanded=\"false\" aria-controls=\"5d3bdfebbe5f528cc\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-2\" data-target=\"#5d3bdfebbe5f528cc\" href=\"#5d3bdfebbe5f528cc\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Puis-je me faire vacciner si je suis enceinte ou si j'allaite mon enfant ? <\/span><\/a><\/h4><\/div><div id=\"5d3bdfebbe5f528cc\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_5d3bdfebbe5f528cc\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div><b>Oui, avec le vaccin PFIZER uniquement (pas avec le vaccin JANSSEN), les femmes enceintes d\u00e8s le premier trimestre peuvent se faire vacciner. <\/b>Au d\u00e9part contre-indiqu\u00e9 par mesure de pr\u00e9caution, nous disposons maintenant de donn\u00e9es solides de s\u00e9curit\u00e9 pour pouvoir recommander la vaccination des femmes enceintes. <strong>La vaccination des femmes enceintes est recommand\u00e9e.<\/strong><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-8a2f48aa5724c993c fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_8a2f48aa5724c993c\"><a aria-expanded=\"false\" aria-controls=\"8a2f48aa5724c993c\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-2\" data-target=\"#8a2f48aa5724c993c\" href=\"#8a2f48aa5724c993c\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est-ce qu\u2019on peut se faire vacciner (Primo ou rappel) apr\u00e8s avoir \u00e9t\u00e9 cas contact asymptomatique apr\u00e8s 10 jours ?<\/span><\/a><\/h4><\/div><div id=\"8a2f48aa5724c993c\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_8a2f48aa5724c993c\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">OUI\u00a0! Uniquement si vous n\u2019avez pas eu de sympt\u00f4mes (asymptomatique)<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-6b32af13ed9d3336e fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6b32af13ed9d3336e\"><a aria-expanded=\"false\" aria-controls=\"6b32af13ed9d3336e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-2\" data-target=\"#6b32af13ed9d3336e\" href=\"#6b32af13ed9d3336e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Apr\u00e8s un test RT-PCR ou antig\u00e9nique n\u00e9gatif, peut-on se faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"6b32af13ed9d3336e\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_6b32af13ed9d3336e\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">OUI\u00a0! Un test n\u00e9gatif signifie que vous n\u2019\u00eates pas porteur du virus. Vous pouvez vous donc vous faire vacciner.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-a0acb2ddb4b0b6bbd fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_a0acb2ddb4b0b6bbd\"><a aria-expanded=\"false\" aria-controls=\"a0acb2ddb4b0b6bbd\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-2\" data-target=\"#a0acb2ddb4b0b6bbd\" href=\"#a0acb2ddb4b0b6bbd\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Apr\u00e8s un test RT-PCR ou antig\u00e9nique n\u00e9gatif, peut-on se faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"a0acb2ddb4b0b6bbd\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_a0acb2ddb4b0b6bbd\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">OUI\u00a0! Un test n\u00e9gatif signifie que vous n\u2019\u00eates pas porteur du virus. Vous pouvez vous donc vous faire vacciner.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-3\"><h2 style=\"text-align: center\" data-fontsize=\"28\" data-lineheight=\"42\">LES VACCINS<\/h2>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-2 fusion_builder_column_inner_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:25px;--awb-padding-right:10px;--awb-padding-bottom:25px;--awb-padding-left:10px;--awb-bg-color:rgba(237,237,237,0.5);--awb-bg-color-hover:rgba(237,237,237,0.5);--awb-bg-blend:screen;--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:2px;--awb-icon-size:18px;--awb-content-font-size:18px;--awb-icon-alignment:right;--awb-hover-color:#f9f9f9;--awb-border-color:#c53466;--awb-background-color:#ffffff;--awb-divider-color:#e0dede;--awb-divider-hover-color:#e0dede;--awb-icon-color:#c53466;--awb-title-color:#1d9bac;--awb-content-color:#4a4e57;--awb-icon-box-color:#333333;--awb-toggle-hover-accent-color:#000000;--awb-title-font-family:&quot;Roboto&quot;;--awb-title-font-weight:400;--awb-title-font-style:normal;--awb-content-font-family:&quot;Roboto&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;\"><div class=\"panel-group fusion-toggle-icon-right fusion-toggle-icon-unboxed\" id=\"accordion-24836-3\"><div class=\"fusion-panel panel-default panel-b08338941c045ef84 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_b08338941c045ef84\"><a aria-expanded=\"false\" aria-controls=\"b08338941c045ef84\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#b08338941c045ef84\" href=\"#b08338941c045ef84\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quels sont les vaccins disponibles contre la Covid-19 et comment fonctionnent-ils ?<\/span><\/a><\/h4><\/div><div id=\"b08338941c045ef84\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_b08338941c045ef84\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Les vaccins contre la Covid-19 actuellement disponibles en Polyn\u00e9sie sont le <strong>PFIZER et le JANSSEN<\/strong>.<\/p>\n<p>Le virus SARS-Cov-2 responsable de la maladie Covid-19 poss\u00e8de une prot\u00e9ine particuli\u00e8re, la prot\u00e9ine S, qui lui permet d\u2019entrer dans les cellules. Lorsque le virus entre dans l\u2019organisme pour la premi\u00e8re fois, le syst\u00e8me immunitaire d\u00e9tecte la pr\u00e9sence de la prot\u00e9ine S, aussi appel\u00e9e antig\u00e8ne, et commence \u00e0 produire des anticorps. Pendant ce temps le virus se multiplie et provoque la maladie entrainant l\u2019apparition de sympt\u00f4mes.<\/p>\n<p>Le PFIZER est un vaccin dit \u00e0 <strong>\u00ab ARN messager \u00bb ou \u00ab ARNm \u00bb<\/strong>. L\u2019ARNm contenu dans le vaccin est le code qui permet au virus de fabriquer la prot\u00e9ine S. Le vaccin ne contient que ce code, aucune autre partie du virus. Lors de l\u2019injection du vaccin, l\u2019ARNm entre dans nos cellules qui vont elles-m\u00eames fabriquer la prot\u00e9ine S. La prot\u00e9ine S n\u2019est qu\u2019une partie du virus, elle ne rend pas malade. Le syst\u00e8me immunitaire va d\u00e9tecter la prot\u00e9ine S, aussi appel\u00e9e antig\u00e8ne, et produire des anticorps contre cette prot\u00e9ine. Par la suite, lorsque le virus SARS-Cov-2 p\u00e9n\u00e8trera dans l\u2019organisme, il sera imm\u00e9diatement reconnu et neutralis\u00e9 par les anticorps, il ne pourra pas se multiplier, la maladie ne se d\u00e9veloppera pas.<\/p>\n<p>Le JANSSEN est un vaccin dit \u00e0<strong> vecteur viral<\/strong>. Le vaccin est compos\u00e9 d\u2019un virus inoffensif (ad\u00e9novirus 26) qui a \u00e9t\u00e9 modifi\u00e9 pour contenir le g\u00e8ne permettant de fabriquer la prot\u00e9ine de pointe S du SARS-CoV-2. Le syst\u00e8me immunitaire de la personne reconna\u00eet la prot\u00e9ine S comme \u00e9trang\u00e8re et produira des anticorps neutralisants et autres.<\/p>\n<p>Les vaccins \u00e0 ARNm et les vaccins reposant sur des vecteurs viraux ne contiennent pas d\u2019adjuvant, leur structure m\u00eame permettant de stimuler le syst\u00e8me immunitaire inn\u00e9.<\/p>\n<p>Les vaccins qui n\u00e9cessitent l\u2019utilisation d\u2019adjuvant sont les vaccins inactiv\u00e9s et les vaccins prot\u00e9iques.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-91a396a16790e2841 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_91a396a16790e2841\"><a aria-expanded=\"false\" aria-controls=\"91a396a16790e2841\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#91a396a16790e2841\" href=\"#91a396a16790e2841\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi autant de vaccins ?<\/span><\/a><\/h4><\/div><div id=\"91a396a16790e2841\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_91a396a16790e2841\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">De nombreux laboratoires ont \u00e9t\u00e9 solicit\u00e9s pour d\u00e9velopper un vaccin contre la covid-19. Plusieurs vaccins utilisant des techniques diff\u00e9rentes ont ainsi \u00e9t\u00e9 d\u00e9velopp\u00e9s (PFIZER, MODERNA, JANSSEN, ASTRAZENECA, etc).<\/span><\/p>\n<p><span style=\"font-weight: 400\">En Polyn\u00e9sie, seuls les vaccins PFIZER et JANSSEN sont propos\u00e9s.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-34dde55ce8ce1c190 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_34dde55ce8ce1c190\"><a aria-expanded=\"false\" aria-controls=\"34dde55ce8ce1c190\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#34dde55ce8ce1c190\" href=\"#34dde55ce8ce1c190\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quelle est la composition des vaccins PFIZER et JANSSEN ?<\/span><\/a><\/h4><\/div><div id=\"34dde55ce8ce1c190\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_34dde55ce8ce1c190\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><strong> Pfizer :<\/strong><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Antig\u00e8ne<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">ARNm COVID-19 (incorpor\u00e9 dans des nanoparticules lipidiques) : 30 microgrammes. <\/span><span style=\"font-weight: 400\">Il s&rsquo;agit de mol\u00e9cules d&rsquo;acide ribonucl\u00e9ique (ARN) messager (ARNm) produit \u00e0 l&rsquo;aide d&rsquo;une transcription <\/span><i><span style=\"font-weight: 400\">in vitro<\/span><\/i><span style=\"font-weight: 400\"> sans cellule \u00e0 partir des matrices d&rsquo;ADN correspondantes, qui codent la prot\u00e9ine virale de spicule (appel\u00e9e prot\u00e9ine Spike ou prot\u00e9ine S) du coronavirus SARS-CoV-2 responsable de la covid 19.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Excipients\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Lipides<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">ALC-0315<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">ALC-0159 Le composant ALC-0159 contient des mol\u00e9cules de poly\u00e9thyl\u00e8ne glycol (PEG). Ces mol\u00e9cules, \u00e9galement pr\u00e9sentes dans des produits cosm\u00e9tiques et m\u00e9dicaments, pourraient \u00eatre \u00e0 l&rsquo;origine des rares cas d&rsquo;anaphylaxie (r\u00e9action allergique grave) qui ont \u00e9t\u00e9 rapport\u00e9s (fr\u00e9quence d&rsquo;environ un cas pour 100 000 vaccinations).<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">1,2- dist\u00e9aroyl-sn-glyc\u00e9ro-3-phosphocholine (DSPC)<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Cholest\u00e9rol<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Autres composants<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Chlorure de sodium<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Chlorure de potassium<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Phosphate monopotassique<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Phosphate disodique dihydrat\u00e9<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Saccharose<\/span><\/li>\n<\/ul>\n<p><strong>JANSSEN :<\/strong><\/p>\n<p><span style=\"font-weight: 400\">Le vaccin consiste en un vecteur ad\u00e9noviral recombinant<\/span><span style=\"font-weight: 400\"> de type 26 (Ad26.COV2-S) incapable de se r\u00e9pliquer et exprimant la glycoprot\u00e9ine Spike* (encore appel\u00e9e prot\u00e9ine S ou prot\u00e9ine de spicule) du coronavirus SARS-CoV-2.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">* : produit dans la lign\u00e9e cellulaire PER.C6 TetR et par la technologie de l&rsquo;ADN recombinant.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Une dose (0,5 mL) contient :<\/span><\/p>\n<ol>\n<li><b> Antig\u00e8ne<\/b><\/li>\n<\/ol>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">au moins de 8,92 log10 unit\u00e9s infectieuses (U.I.)<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Le produit contient des organismes g\u00e9n\u00e9tiquement modifi\u00e9s (OGM).<\/span><\/p>\n<ol start=\"2\">\n<li><b> Excipients<\/b><\/li>\n<\/ol>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Acide citrique monohydrat\u00e9<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Citrate trisodique dihydrat\u00e9 (uniquement pour les pr\u00e9sentations en bo\u00eete de 10 flacons)<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">\u00c9thanol (environ 2 mg par dose, soit une quantit\u00e9 faible sans effets notables)<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">2-hydroxypropyl-\u03b2-cyclodextrine (HBCD)<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Polysorbate 80<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Chlorure de sodium (moins de 1 mmol de sodium par dose de 0,5 mL, soit 23 mg, c&rsquo;est-\u00e0-dire qu&rsquo;il peut \u00eatre consid\u00e9r\u00e9 comme \u00e9tant \u00ab\u00a0sans sodium\u00a0\u00bb)<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Hydroxyde de sodium<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Acide chlorhydrique<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-15a96f368d55c45c8 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_15a96f368d55c45c8\"><a aria-expanded=\"false\" aria-controls=\"15a96f368d55c45c8\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#15a96f368d55c45c8\" href=\"#15a96f368d55c45c8\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Une dose de vaccin est-elle suffisante ?<\/span><\/a><\/h4><\/div><div id=\"15a96f368d55c45c8\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_15a96f368d55c45c8\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div>\n<div><strong>Pour le Vaccin PFIZER, NON<\/strong>.\u00a0Quand le sch\u00e9ma de vaccination doit s\u2019effectuer en deux doses, il est recommand\u00e9 de faire les deux doses en respectant l\u2019intervalle de temps recommand\u00e9 entre les deux. En effet, c\u2019est apr\u00e8s deux injections que l\u2019on obtient la plus grande efficacit\u00e9. Aussi, apr\u00e8s deux doses, l\u2019immunog\u00e9nicit\u00e9, c\u2019est-\u00e0-dire notre capacit\u00e9 \u00e0 r\u00e9agir face au virus s\u2019il venait \u00e0 nous infecter par la suite, serait 10 \u00e0 100 fois sup\u00e9rieure, offrant une protection plus prolong\u00e9e dans le temps.<\/div>\n<\/div>\n<div><\/div>\n<div><strong>Pour le Vaccin Janssen, OUI<\/strong>. Le sch\u00e9ma de vaccination s\u2019effectue en une seule dose. Une seule dose est n\u00e9cessaire pour obtenir la plus grande efficacit\u00e9.<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-21cebfff2056c9614 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_21cebfff2056c9614\"><a aria-expanded=\"false\" aria-controls=\"21cebfff2056c9614\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#21cebfff2056c9614\" href=\"#21cebfff2056c9614\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quels sont les effets secondaires\/ind\u00e9sirables du vaccin ?<\/span><\/a><\/h4><\/div><div id=\"21cebfff2056c9614\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_21cebfff2056c9614\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Comme tous les m\u00e9dicaments, les vaccins peuvent entra\u00eener des effets ind\u00e9sirables.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ils sont classiques, relativement fr\u00e9quents et communs \u00e0 tous les vaccins : douleur au point d\u2019injection, fatigue, maux de t\u00eate, douleurs musculaires ou articulaires, frissons ou fi\u00e8vre.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ces\u00a0effets secondaires\/ind\u00e9sirables\u00a0montrent que votre syst\u00e8me immunitaire est en train de r\u00e9agir pour se d\u00e9fendre contre l\u2019antig\u00e8ne.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ils sont souvent l\u00e9gers et ne durent que quelques jours.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Si des effets deviennent g\u00eanants ou\u00a0importants, il faut le signaler \u00e0 son m\u00e9decin traitant qui d\u00e9clarera la situation si n\u00e9c\u00e9ssaire \u00e0 l\u2019ARASS (Agence de r\u00e9gulation de l&rsquo;action sanitaire et sociale).<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-6a72726b53f3d2466 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6a72726b53f3d2466\"><a aria-expanded=\"false\" aria-controls=\"6a72726b53f3d2466\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#6a72726b53f3d2466\" href=\"#6a72726b53f3d2466\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Les mutations du virus peuvent-elles rendre le vaccin inefficace ?<\/span><\/a><\/h4><\/div><div id=\"6a72726b53f3d2466\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_6a72726b53f3d2466\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>C\u2019est possible mais peu probable. Le SARS-Cov-2 mute r\u00e9guli\u00e8rement comme tous les virus, mais aucune mutation d\u00e9tect\u00e9e \u00e0 ce jour n\u2019a affect\u00e9 la prot\u00e9ine S (sur laquelle est bas\u00e9e le vaccin) au point d\u2019alt\u00e9rer la capacit\u00e9 du corps humain \u00e0 la reconna\u00eetre. Les mutations du SARS-Cov-2 sont surveill\u00e9es de tr\u00e8s pr\u00e8s par les scientifiques, qui travailleront \u00e0 l\u2019adaptation du vaccin en cas de mutation importante.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-a7f5be0fd02d8ee05 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_a7f5be0fd02d8ee05\"><a aria-expanded=\"false\" aria-controls=\"a7f5be0fd02d8ee05\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#a7f5be0fd02d8ee05\" href=\"#a7f5be0fd02d8ee05\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Les vaccins utilis\u00e9s sont-ils s\u00fbrs ?<\/span><\/a><\/h4><\/div><div id=\"a7f5be0fd02d8ee05\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_a7f5be0fd02d8ee05\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Tous les vaccins autoris\u00e9s en Polyn\u00e9sie fran\u00e7aise font l\u2019objet d\u2019un contr\u00f4le rigoureux pour s\u2019assurer de leur efficacit\u00e9 et de leur s\u00fbret\u00e9. De plus, une fois disponible sur le Fenua, nous continuerons \u00e0 les surveiller afin de s\u2019assurer de leur suret\u00e9.<\/p>\n<p>Pour en savoir plus sur la surveillance de ces vaccins en pratique, consulter le site de l\u2019ARASS\u00a0\u00bb avec le lien suivant\u00a0:\u00a0<a href=\"https:\/\/www.service-public.pf\/arass\/pharmacovigilance-des-vaccins-contre-la-covid-19\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.service-public.pf\/arass\/pharmacovigilance-des-vaccins-contre-la-covid-19\/&amp;source=gmail&amp;ust=1611088412047000&amp;usg=AFQjCNE-j5ImLLzKl-UCnN1rfNtk-cdVUw\">https:\/\/www.service-public.pf\/arass\/pharmacovigilance-des-vaccins-contre-la-covid-19\/<\/a><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-39e4d670eb4ef5d1e fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_39e4d670eb4ef5d1e\"><a aria-expanded=\"false\" aria-controls=\"39e4d670eb4ef5d1e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#39e4d670eb4ef5d1e\" href=\"#39e4d670eb4ef5d1e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Les vaccins \u00e0 ARN sont nouveaux mais sont-ils s\u00fbr ?<\/span><\/a><\/h4><\/div><div id=\"39e4d670eb4ef5d1e\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_39e4d670eb4ef5d1e\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Aucun vaccin \u00e0 ARN n\u2019avait \u00e9t\u00e9 homologu\u00e9 avant le vaccin contre la Covid-19, mais ces vaccins font l\u2019objet d\u2019\u00e9tudes depuis une vingtaine d\u2019ann\u00e9es et plusieurs essais cliniques y compris chez l\u2019humain avaient d\u00e9j\u00e0 \u00e9t\u00e9 men\u00e9s.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-88c4d076ce2b04c09 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_88c4d076ce2b04c09\"><a aria-expanded=\"false\" aria-controls=\"88c4d076ce2b04c09\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#88c4d076ce2b04c09\" href=\"#88c4d076ce2b04c09\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est-ce que je peux avoir les deux vaccins pour \u00eatre encore plus prot\u00e9g\u00e9 ?<\/span><\/a><\/h4><\/div><div id=\"88c4d076ce2b04c09\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_88c4d076ce2b04c09\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Le Vaccin PFIZER et le vaccin JANSSEN sont les seuls propos\u00e9s en Polyn\u00e9sie.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Vous pouvez donc choisir entre l\u2019un et l\u2019autre, mais pas les deux.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Il est possible qu\u2019un rappel soit recommand\u00e9 prochainement pour une meilleure protection, mais cela sera confirm\u00e9 ult\u00e9rieurement.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-ad698b34540d5e120 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_ad698b34540d5e120\"><a aria-expanded=\"false\" aria-controls=\"ad698b34540d5e120\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#ad698b34540d5e120\" href=\"#ad698b34540d5e120\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Le vaccin (PFIZER ou JANSSEN) met combien de temps pour agir ?<\/span><\/a><\/h4><\/div><div id=\"ad698b34540d5e120\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_ad698b34540d5e120\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Le Vaccin PFIZER est efficace \u00e0 95%, 7 jours apr\u00e8s la deuxi\u00e8me dose.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le Vaccin JANSSEN est efficace \u00e0 68%, 14 jours apr\u00e8s la seule et unique dose.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-69cb535cb5728e45e fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_69cb535cb5728e45e\"><a aria-expanded=\"false\" aria-controls=\"69cb535cb5728e45e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#69cb535cb5728e45e\" href=\"#69cb535cb5728e45e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quelles sont les contre-indications de la vaccination ?<\/span><\/a><\/h4><\/div><div id=\"69cb535cb5728e45e\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_69cb535cb5728e45e\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Un ant\u00e9c\u00e9dent de<\/span><a href=\"https:\/\/www.mesvaccins.net\/textes\/20210611_cosv_covid_vacc_enfants_PIMS.pdf\"> <span style=\"font-weight: 400\">syndrome inflammatoire multi-syst\u00e9mique p\u00e9diatrique<\/span><\/a><span style=\"font-weight: 400\"> (PIMS), une complication extr\u00eamement rare qui a atteint certains enfants et adolescents \u00e0 la suite d&rsquo;une infection par le SARS-CoV-2.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Un ant\u00e9c\u00e9dent de myocardite, de p\u00e9ricardite ou d&rsquo;h\u00e9patite grave ayant n\u00e9cessit\u00e9 une hospitalisation et faisant suite \u00e0 une premi\u00e8re injection de vaccin d&rsquo;ARNm.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Une allergie \u00e0 l&rsquo;un des composants du vaccin, le PEG 2000 ou poly\u00e9thyl\u00e8ne glycol, une situation qui concernerait \u00e0 peu pr\u00e8s 10 cas en France selon le ministre de la Sant\u00e9.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Une allergie de type anaphylactique \u00e0 un composant du vaccin ou une r\u00e9action anaphylactique survenue apr\u00e8s une premi\u00e8re dose de vaccin.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Le vaccin<\/span><a href=\"https:\/\/www.mesvaccins.net\/web\/vaccines\/650-vaxzevria-covid-19-vaccine-astrazeneca\"> <span style=\"font-weight: 400\">Vaxzevria<\/span><\/a><span style=\"font-weight: 400\"> (AstraZeneca) est sp\u00e9cifiquement contre-indiqu\u00e9 chez les personnes qui ont pr\u00e9sent\u00e9 un syndrome thrombotique thrombocytop\u00e9nique (STT) suite \u00e0 la vaccination par Vaxzevria et chez des personnes ayant d\u00e9j\u00e0 pr\u00e9sent\u00e9 des \u00e9pisodes de syndrome de fuite capillaire.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Le vaccin<\/span><a href=\"https:\/\/www.mesvaccins.net\/web\/vaccines\/666-janssen-covid-19-vaccine#vaccin_contre-indications\"> <span style=\"font-weight: 400\">Janssen COVID-19 Vaccine<\/span><\/a><span style=\"font-weight: 400\"> est contre-indiqu\u00e9 chez les personnes ayant pr\u00e9sent\u00e9 des \u00e9pisodes de syndrome de fuite capillaire.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Ni la grossesse, ni un \u00ab ant\u00e9c\u00e9dent d&rsquo;allergie \u00e0 un antibiotique ou une piq\u00fbre d&rsquo;abeille \u00bb ne constituent des contre-indications \u00e0 la vaccination.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-9210fe53e4fa3b103 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_9210fe53e4fa3b103\"><a aria-expanded=\"false\" aria-controls=\"9210fe53e4fa3b103\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#9210fe53e4fa3b103\" href=\"#9210fe53e4fa3b103\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi apr\u00e8s avoir eu la covid-19, les anticorps ne sont pas suffisants et on doit donc se faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"9210fe53e4fa3b103\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_9210fe53e4fa3b103\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Les anticorps sont suffisants, mais on ne sait pas pendant combien de temps. La vaccination agit comme un rappel permettant de prolonger la dur\u00e9e de l\u2019immunit\u00e9, et de la renforcer.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-03585f5306a0806c4 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_03585f5306a0806c4\"><a aria-expanded=\"false\" aria-controls=\"03585f5306a0806c4\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-3\" data-target=\"#03585f5306a0806c4\" href=\"#03585f5306a0806c4\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Doit-on recevoir une deuxi\u00e8me dose (Vaccin PFIZER) apr\u00e8s avoir \u00e9t\u00e9 positif \u00e0 la covid-19 ? Si oui, combien de temps apr\u00e8s ?<\/span><\/a><\/h4><\/div><div id=\"03585f5306a0806c4\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_03585f5306a0806c4\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">OUI\u00a0! Il faut attendre 2 \u00e0 6 mois pour recevoir votre deuxi\u00e8me dose \u00e0 partir du jour de pr\u00e9l\u00e8vement positif.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-top:-2%;margin-bottom:3%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#c53466;border-color:#c53466;border-top-width:7px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-4\"><h2 style=\"text-align: center\" data-fontsize=\"28\" data-lineheight=\"42\">ID\u00c9ES RE\u00c7UES ET D\u00c9SINFORMATION<\/h2>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-top:-2%;margin-bottom:3%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#c53466;border-color:#c53466;border-top-width:7px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-3 fusion_builder_column_inner_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:25px;--awb-padding-right:10px;--awb-padding-bottom:25px;--awb-padding-left:10px;--awb-bg-color:rgba(237,237,237,0.5);--awb-bg-color-hover:rgba(237,237,237,0.5);--awb-bg-blend:screen;--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:2px;--awb-icon-size:18px;--awb-content-font-size:18px;--awb-icon-alignment:right;--awb-hover-color:#f9f9f9;--awb-border-color:#c53466;--awb-background-color:#ffffff;--awb-divider-color:#e0dede;--awb-divider-hover-color:#e0dede;--awb-icon-color:#c53466;--awb-title-color:#1d9bac;--awb-content-color:#4a4e57;--awb-icon-box-color:#333333;--awb-toggle-hover-accent-color:#000000;--awb-title-font-family:&quot;Roboto&quot;;--awb-title-font-weight:400;--awb-title-font-style:normal;--awb-content-font-family:&quot;Roboto&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;\"><div class=\"panel-group fusion-toggle-icon-right fusion-toggle-icon-unboxed\" id=\"accordion-24836-4\"><div class=\"fusion-panel panel-default panel-213c4ada2c5ae24ad fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_213c4ada2c5ae24ad\"><a aria-expanded=\"false\" aria-controls=\"213c4ada2c5ae24ad\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-4\" data-target=\"#213c4ada2c5ae24ad\" href=\"#213c4ada2c5ae24ad\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Le virus SARS-Cov-2 a-t-il pu \u00eatre fabriqu\u00e9 artificiellement dans un laboratoire ?<\/span><\/a><\/h4><\/div><div id=\"213c4ada2c5ae24ad\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_213c4ada2c5ae24ad\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Non. Les \u00e9tudes g\u00e9n\u00e9tiques sur le virus permettent de retracer son histoire. Elles d\u00e9montrent irr\u00e9futablement que le virus n\u2019a pas \u00e9t\u00e9 fabriqu\u00e9 par manipulation dans un laboratoire.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-e995839e7b6750c15 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_e995839e7b6750c15\"><a aria-expanded=\"false\" aria-controls=\"e995839e7b6750c15\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-4\" data-target=\"#e995839e7b6750c15\" href=\"#e995839e7b6750c15\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Y-a-t-il des adjuvants, m\u00e9taux lourds ou de l\u2019aluminium dans les vaccins utilis\u00e9s ?<\/span><\/a><\/h4><\/div><div id=\"e995839e7b6750c15\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_e995839e7b6750c15\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><strong>Non.<\/strong> Il n\u2019y a ni adjuvant, ni m\u00e9taux lourds, ni d\u2019aluminium dans les vaccins utilis\u00e9s actuellement.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-f719921fc64fcfd0f fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_f719921fc64fcfd0f\"><a aria-expanded=\"false\" aria-controls=\"f719921fc64fcfd0f\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-4\" data-target=\"#f719921fc64fcfd0f\" href=\"#f719921fc64fcfd0f\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est-ce que le vaccin \u00e0 ARN messager (PFIZER) peut modifier l\u2019ADN ?<\/span><\/a><\/h4><\/div><div id=\"f719921fc64fcfd0f\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_f719921fc64fcfd0f\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Non !<\/span><span style=\"font-weight: 400\">\u00a0Lors de l\u2019expression des g\u00e8nes, l\u2019information circule uniquement dans le sens ADN \u00e0 ARN. Par ailleurs, il n\u2019est pas non plus possible que le contenu des vaccins \u00e0 ARNm entre dans le noyau de nos cellules o\u00f9 se trouve notre ADN. L&rsquo;ARNm vient de l&rsquo;ADN mais n&rsquo;y retourne pas !<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-b823abc2c964e4e7a fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_b823abc2c964e4e7a\"><a aria-expanded=\"false\" aria-controls=\"b823abc2c964e4e7a\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-4\" data-target=\"#b823abc2c964e4e7a\" href=\"#b823abc2c964e4e7a\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\"> Est-ce qu\u2019il y a des nanoparticules 5G dans les vaccins PFIZER et JANSSEN ?<\/span><\/a><\/h4><\/div><div id=\"b823abc2c964e4e7a\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_b823abc2c964e4e7a\"><div class=\"panel-body toggle-content fusion-clearfix\"><span style=\"font-weight: 400\">NON !\u00a0Ceci est une FAKE NEWS !<\/span><\/p>\n<p><span style=\"font-weight: 400\">Il s\u2019agit de nanoparticules lipidiques (voir la composition du vaccin).<\/span><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-d5d09af3ee4337c51 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_d5d09af3ee4337c51\"><a aria-expanded=\"false\" aria-controls=\"d5d09af3ee4337c51\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-4\" data-target=\"#d5d09af3ee4337c51\" href=\"#d5d09af3ee4337c51\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Comment un vaccin peut-il \u00eatre d\u00e9velopp\u00e9 si rapidement ? Pourquoi ce n\u2019est pas le cas pour des maladies connues comme le VIH, le Cancer, etc ?<\/span><\/a><\/h4><\/div><div id=\"d5d09af3ee4337c51\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_d5d09af3ee4337c51\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Parce que tous les laboratoires se sont saisis du probl\u00e8me Covid-19, que les moyens (humains et financiers) ont \u00e9t\u00e9 mis \u00e0 disposition des chercheurs et que tous les laboratoires ont collabor\u00e9 ensemble. D&rsquo;autre part,\u00a0 la technique de l&rsquo;A<\/span><span style=\"font-weight: 400\">RN <\/span><span style=\"font-weight: 400\">messager est utilis\u00e9e depuis plus de 40 ans, elle est aujourd\u2019hui ma\u00eetris\u00e9e et la technique plus classique des vaccins \u00e0 vecteur viral (Janssen) est aussi tr\u00e8s connue et ma\u00eetris\u00e9e.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-57a16b7df2f511d50 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_57a16b7df2f511d50\"><a aria-expanded=\"false\" aria-controls=\"57a16b7df2f511d50\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-4\" data-target=\"#57a16b7df2f511d50\" href=\"#57a16b7df2f511d50\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est-ce que le vaccin rend magn\u00e9tique ? Comme la pi\u00e8ce ou le t\u00e9l\u00e9phone qui colle sur le bras.<\/span><\/a><\/h4><\/div><div id=\"57a16b7df2f511d50\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_57a16b7df2f511d50\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">NON ! Ceci est une fake News !<\/span><\/p>\n<p><span style=\"font-weight: 400\">La composition des vaccins ne pr\u00e9sente aucun composant magn\u00e9tique.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le fait d\u2019avoir un objet qui peut coller sur la peau s\u2019explique par (dans certains cas) la tenue en s\u00e9bum de votre peau.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Plus la peau sera grasse, plus les objets \u00e0 face plate pourront coller.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Aussi, une r\u00e9action inflammatoire peut se produit sur le point d\u2019injection du vaccin, donnant une peau plus chaude et donc plus encline \u00e0 ces ph\u00e9nom\u00e8nes de ventouse.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-ce11caa7d67be5d06 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_ce11caa7d67be5d06\"><a aria-expanded=\"false\" aria-controls=\"ce11caa7d67be5d06\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-4\" data-target=\"#ce11caa7d67be5d06\" href=\"#ce11caa7d67be5d06\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Le vaccin est toujours en phase de test ! Nous sommes des cobayes !?<\/span><\/a><\/h4><\/div><div id=\"ce11caa7d67be5d06\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_ce11caa7d67be5d06\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Les vaccins contre la Covid ont tous \u00e9t\u00e9 test\u00e9s.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Cela fait bien longtemps que la phase de test est termin\u00e9e.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Les tests ont largement prouv\u00e9 leur efficacit\u00e9 et leur innocuit\u00e9.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-289817d8ee21d99dd fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_289817d8ee21d99dd\"><a aria-expanded=\"false\" aria-controls=\"289817d8ee21d99dd\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-4\" data-target=\"#289817d8ee21d99dd\" href=\"#289817d8ee21d99dd\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Le vaccin peut rendre infertile ?<\/span><\/a><\/h4><\/div><div id=\"289817d8ee21d99dd\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_289817d8ee21d99dd\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">NON ! De nombreux essais complets ont \u00e9t\u00e9 r\u00e9alis\u00e9s sp\u00e9cifiquement sur des femmes enceintes pour la vaccination.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Aucun effet n\u00e9faste n\u2019a \u00e9t\u00e9 enregistr\u00e9 pour la m\u00e8re ou pour le foetus.<\/span><\/p>\n<p><span style=\"font-weight: 400\">C\u2019est \u00e9galement le cas chez les hommes pour qui la qualit\u00e9 du sperme n\u2019a connu aucune diff\u00e9rence avant et apr\u00e8s le vaccin.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-551e44b5010155e49 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_551e44b5010155e49\"><a aria-expanded=\"false\" aria-controls=\"551e44b5010155e49\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-4\" data-target=\"#551e44b5010155e49\" href=\"#551e44b5010155e49\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi dit-on que les laboratoires sont d\u00e9charg\u00e9s de leur responsabilit\u00e9s ?<\/span><\/a><\/h4><\/div><div id=\"551e44b5010155e49\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_551e44b5010155e49\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Ceci est une fausse rumeur ! En cas d\u2019effet ind\u00e9sirable grave, le laboratoire concern\u00e9 sera tenu responsable \u00e0 condition de prouver le lien de cause \u00e0 effet du vaccin et de l\u2019effet ind\u00e9sirables. (Ex: avoir un probl\u00e8me au genoux en tombant et d\u00e9noncer le vaccin).<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le laboratoire lui, doit apporter la preuve qu\u2019il a tout \u00e0 fait pour \u00e9viter cet effets ind\u00e9sirables grave, conform\u00e9ment \u00e0 la r\u00e9glementation europ\u00e9enne.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Non, le laboratoire n\u2019est pas d\u00e9charg\u00e9 de sa responsabilit\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Oui, le victime peut \u00eatre indemnis\u00e9 le cas \u00e9chant.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:900px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"1989\" height=\"478\" title=\"Gestes Barrieres Vaccin\" src=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin.png\" alt class=\"img-responsive wp-image-18507\" srcset=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin-200x48.png 200w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin-400x96.png 400w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin-600x144.png 600w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin-800x192.png 800w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin-1200x288.png 1200w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin.png 1989w\" sizes=\"(max-width: 1100px) 100vw, 1200px\" \/><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-5\"><p><u><strong><a href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/professionnels-sante-covid-19\/\">Vous \u00eates professionnel de sant\u00e9, consultez la documentation sur la vaccination COVID-19, en cliquant sur ce lien.<\/a><\/strong><\/u><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_4 1_4 fusion-one-fourth fusion-column-last fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-padding-right:10px;--awb-padding-left:10px;--awb-bg-color:#f7f7f7;--awb-bg-color-hover:#f7f7f7;--awb-bg-size:cover;--awb-margin-bottom:0px;width:25%;width:calc(25% - ( ( 4% ) * 0.25 ) );\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-6\"><h3 style=\"text-align: center\" data-fontsize=\"22\" data-lineheight=\"33\">PLUS D&rsquo;INFORMATIONS<\/h3>\n<div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-no-small-visibility fusion-no-medium-visibility\" style=\"margin-left: auto;margin-right: auto;margin-top:-5%;margin-bottom:4%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#3abfbf;border-color:#3abfbf;border-top-width:5px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-1 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Coronavirus COVID-19<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-2 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/espace-grand-public-covid\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Espace Grand Public<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-3 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/professionnels-sante-covid-19\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Espace professionnels de sant\u00e9<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-4 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/espace-entreprise-covid\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">ESPACE ENTREPRISES<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-5 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/espace-voyageurs\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">ESPACE VOYAGEURS<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-6 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/espace-commune\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">ESPACE COMMUNES<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-7 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/questions-frequentes\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Questions fr\u00e9quentes<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:4%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:400px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/professionnels-sante-covid-19\/\" target=\"_self\" aria-label=\"Professionnel Vaccination\"><img decoding=\"async\" width=\"619\" height=\"438\" src=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/professionnel-vaccination.png\" alt class=\"img-responsive wp-image-18608\" srcset=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/professionnel-vaccination-200x142.png 200w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/professionnel-vaccination-400x283.png 400w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/professionnel-vaccination-600x425.png 600w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/professionnel-vaccination.png 619w\" sizes=\"(max-width: 1100px) 100vw, 400px\" \/><\/a><\/span><\/div><\/div><div class=\"fusion-text fusion-text-7\"><h3 style=\"text-align: center\" data-fontsize=\"22\" data-lineheight=\"33\">SUIVEZ-NOUS<\/h3>\n<div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-no-small-visibility fusion-no-medium-visibility\" style=\"margin-left: auto;margin-right: auto;margin-top:-5%;margin-bottom:4%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#3abfbf;border-color:#3abfbf;border-top-width:5px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div>\n<\/div><div class=\"fusion-widget-area awb-widget-area-element fusion-widget-area-1 fusion-content-widget-area\" style=\"--awb-title-color:#333333;--awb-padding:0px 0px 0px 0px;\">\n\t\t<section id=\"recent-posts-7\" class=\"widget widget_recent_entries\">\n\t\t<div class=\"heading\"><h4 class=\"widget-title\">Articles r\u00e9cents<\/h4><\/div>\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.service-public.pf\/dsp\/2026\/05\/12\/bulletin-de-surveillance-sanitaire-de-la-s18-2026\/\">Bulletin de Surveillance Sanitaire de la S18 2026<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.service-public.pf\/dsp\/2026\/05\/04\/bulletin-de-surveillance-sanitaire-de-la-s17-2026\/\">Bulletin de Surveillance Sanitaire de la S17 2026<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.service-public.pf\/dsp\/2026\/04\/27\/bulletin-de-surveillance-sanitaire-de-la-s16-2026\/\">Bulletin de Surveillance Sanitaire de la S16 2026<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.service-public.pf\/dsp\/2026\/04\/20\/bulletin-de-surveillance-sanitaire-de-la-s15-2026\/\">Bulletin de Surveillance Sanitaire de la S15 2026<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.service-public.pf\/dsp\/2026\/04\/13\/bulletin-de-surveillance-sanitaire-de-la-s14-2026\/\">Bulletin de Surveillance Sanitaire de la S14 2026<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t<\/section><div class=\"fusion-additional-widget-content\"><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:40px;--awb-padding-right:10px;--awb-padding-left:10px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-one\" style=\"--awb-text-color:#ffffff;--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;--awb-font-size:60px;\" id=\"titre-conteneur\"><h1 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:60;line-height:1.4;\">FAQ VACCINATION COVID-19<\/h1><\/div><div class=\"fusion-text fusion-text-8\"><h2 style=\"text-align: center\" data-fontsize=\"28\" data-lineheight=\"42\">L&rsquo;OBLIGATION VACCINALE<\/h2>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-top:-2%;margin-bottom:3%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#c53466;border-color:#c53466;border-top-width:7px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-aligncenter\"><a class=\"fusion-button button-flat button-xlarge button-custom fusion-button-default button-8 fusion-button-default-span \" style=\"--button_accent_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_gradient_top_color:#463492;--button_gradient_bottom_color:#463492;--button_gradient_top_color_hover:#4a167b;--button_gradient_bottom_color_hover:#4a167b;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/trav\/wp-content\/uploads\/sites\/23\/2021\/09\/FAQ-ObligationVaccinale-2021-08-31.pdf\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">FAQ \u2013 Loi du pays relative \u00e0 l\u2019obligation de vaccination<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:20px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-9\"><p style=\"text-align: center\"><em><strong>Retrouvez toutes les informations sur l&rsquo;obligation vaccinale sur le site de la Direction du travail<\/strong><\/em><\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-10\"><h2 style=\"text-align: center\" data-fontsize=\"28\" data-lineheight=\"42\">INFORMATIONS G\u00c9N\u00c9RALES<\/h2>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-top:-2%;margin-bottom:3%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#c53466;border-color:#c53466;border-top-width:7px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-4 fusion_builder_column_inner_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:25px;--awb-padding-right:10px;--awb-padding-bottom:25px;--awb-padding-left:10px;--awb-bg-color:rgba(237,237,237,0.5);--awb-bg-color-hover:rgba(237,237,237,0.5);--awb-bg-blend:screen;--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:2px;--awb-icon-size:18px;--awb-content-font-size:18px;--awb-icon-alignment:right;--awb-hover-color:#f9f9f9;--awb-border-color:#c53466;--awb-background-color:#ffffff;--awb-divider-color:#e0dede;--awb-divider-hover-color:#e0dede;--awb-icon-color:#c53466;--awb-title-color:#1d9bac;--awb-content-color:#4a4e57;--awb-icon-box-color:#333333;--awb-toggle-hover-accent-color:#000000;--awb-title-font-family:&quot;Roboto&quot;;--awb-title-font-weight:400;--awb-title-font-style:normal;--awb-content-font-family:&quot;Roboto&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;\"><div class=\"panel-group fusion-toggle-icon-right fusion-toggle-icon-unboxed\" id=\"accordion-24836-5\"><div class=\"fusion-panel panel-default panel-6c63932427a57b673 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6c63932427a57b673\"><a aria-expanded=\"false\" aria-controls=\"6c63932427a57b673\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#6c63932427a57b673\" href=\"#6c63932427a57b673\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Qu'est-ce qu'un vaccin et la vaccination ?<\/span><\/a><\/h4><\/div><div id=\"6c63932427a57b673\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_6c63932427a57b673\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Les vaccins sont des <strong>m\u00e9dicaments inject\u00e9s \u00e0 des personnes non malades pour stimuler leur syst\u00e8me immunitaire et les prot\u00e9ger contre une maladie.<\/strong> Ils sont compos\u00e9s de microbes tu\u00e9 (virus ou bact\u00e9ries) ou de fragments de microbes appel\u00e9s \u00ab antig\u00e8nes \u00bb, que le syst\u00e8me immunitaire va d\u00e9tecter comme \u00ab intrus \u00bb et chercher \u00e0 \u00e9liminer. Lors de la vaccination, le syst\u00e8me immunitaire apprend \u00e0 reconnaitre l\u2019antig\u00e8ne \u00e9tranger et produit des anticorps sp\u00e9cifiques contre cet antig\u00e8ne. Par la suite, lorsque le vrai microbe p\u00e9n\u00e8tre dans l\u2019organisme, il est imm\u00e9diatement reconnu et neutralis\u00e9 par les anticorps, la maladie ne se d\u00e9veloppe pas.<\/p>\n<p><strong>Se faire vacciner c\u2019est se prot\u00e9ger soi contre des maladies dont les complications peuvent \u00eatre graves voire mortelles mais c\u2019est aussi prot\u00e9ger les autres. En \u00e9vitant la maladie, on diminue le risque de contaminer les autres.<\/strong><\/p>\n<p>Lorsque qu\u2019une part importante de la population est vaccin\u00e9e, on parle d\u2019<strong>immunit\u00e9 collective ou de groupe<\/strong>. Les personnes vaccin\u00e9es, en ne participant pas \u00e0 la propagation du virus, emp\u00eachent celui-ci de circuler, ce qui permet de prot\u00e9ger aussi ceux qui ne peuvent pas \u00eatre vaccin\u00e9s ou qui sont moins bien prot\u00e9g\u00e9s par les vaccins.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-0ae6956a15531f1ac fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_0ae6956a15531f1ac\"><a aria-expanded=\"false\" aria-controls=\"0ae6956a15531f1ac\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#0ae6956a15531f1ac\" href=\"#0ae6956a15531f1ac\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi me faire vacciner contre la COVID-19 ?<\/span><\/a><\/h4><\/div><div id=\"0ae6956a15531f1ac\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_0ae6956a15531f1ac\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>La vaccination contre la Covid-19 est efficace \u00e0 plus de 90% contre le risque de survenue de formes graves de la maladie. Elle permet d\u2019\u00e9viter de d\u00e9velopper des sympt\u00f4mes importants qui pourraient n\u00e9cessiter une hospitalisation voire une r\u00e9animation.<\/p>\n<p><b>Des premiers r\u00e9sultats d&rsquo;\u00e9tudes en cours permettent aussi de dire que les vaccins dont nous disposons permettent de diminuer la transmission du virus \u00e0 d&rsquo;autres personnes (nous sommes moins voire non contagieux pour les autres). Par cons\u00e9quent, en nous vaccinant, nous nous prot\u00e9geons de la maladie mais aussi les autres, en ne leur transmettant pas le virus.\u00a0<\/b><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-cc7f65f8d9edc440b fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_cc7f65f8d9edc440b\"><a aria-expanded=\"false\" aria-controls=\"cc7f65f8d9edc440b\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#cc7f65f8d9edc440b\" href=\"#cc7f65f8d9edc440b\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00c0 quoi \u00e7a sert de se faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"cc7f65f8d9edc440b\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_cc7f65f8d9edc440b\"><div class=\"panel-body toggle-content fusion-clearfix\"><span style=\"font-weight: 400\">Se faire vacciner c\u2019est se prote\u0301ger contre la maladie et les complications qui peuvent e\u0302tre graves, voire mortelles.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La vaccination permet aussi de prot\u00e9ger les autres en diminuant le risque de les contaminer.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Toutes les personnes vaccine\u0301es empe\u0302chent la circulation du virus et prote\u0300ge ainsi ceux qui ne peuvent pas e\u0302tre vaccine\u0301s ou qui sont moins bien prote\u0301ge\u0301s par le vaccin (personnes \u00e2g\u00e9es, personnes avec des longues maladies, etc)<\/span><\/p>\n<p><span style=\"font-weight: 400\">Lorsqu&rsquo;une part importante de la population est vaccine\u0301e, on parle d\u2019immunite\u0301 collective (ou de groupe).<\/span><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-e51388cbeef3a85cc fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_e51388cbeef3a85cc\"><a aria-expanded=\"false\" aria-controls=\"e51388cbeef3a85cc\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#e51388cbeef3a85cc\" href=\"#e51388cbeef3a85cc\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est ce que le vaccin est gratuit ?<\/span><\/a><\/h4><\/div><div id=\"e51388cbeef3a85cc\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_e51388cbeef3a85cc\"><div class=\"panel-body toggle-content fusion-clearfix\"><span style=\"font-weight: 400\">OUI ! La vaccination est gratuite depuis son lancement en Polyn\u00e9sie fran\u00e7aise en janvier 2021.<\/span><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-8e3ffa7e045e1ecb6 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_8e3ffa7e045e1ecb6\"><a aria-expanded=\"false\" aria-controls=\"8e3ffa7e045e1ecb6\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#8e3ffa7e045e1ecb6\" href=\"#8e3ffa7e045e1ecb6\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">O\u00f9 sont situ\u00e9s les centres de vaccination ?<\/span><\/a><\/h4><\/div><div id=\"8e3ffa7e045e1ecb6\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_8e3ffa7e045e1ecb6\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Les centres de vaccination sont d\u00e9ploy\u00e9s sur Tahiti, Moorea et dans les \u00eeles \u00e9loign\u00e9es<\/span><\/p>\n<p><span style=\"font-weight: 400\">La liste compl\u00e8te est disponible sur le site internet de la Direction de la sant\u00e9 :\u00a0<\/span><a href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/vaccination-covid\/\"><span style=\"font-weight: 400\">https:\/\/www.service-public.pf\/dsp\/covid-19\/vaccination-covid\/<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400\">Des vaccinodromes sont \u00e9galement organis\u00e9s r\u00e9guli\u00e8rement dans certaines communes.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-443f2273c4145c4a6 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_443f2273c4145c4a6\"><a aria-expanded=\"false\" aria-controls=\"443f2273c4145c4a6\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#443f2273c4145c4a6\" href=\"#443f2273c4145c4a6\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est-ce que les vaccinodromes proposent les deux vaccins ?<\/span><\/a><\/h4><\/div><div id=\"443f2273c4145c4a6\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_443f2273c4145c4a6\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">OUI ! Tous les vaccinodromes d\u00e9ploy\u00e9s proposent les deux vaccins.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-6d69ca7dbf01d8a17 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6d69ca7dbf01d8a17\"><a aria-expanded=\"false\" aria-controls=\"6d69ca7dbf01d8a17\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#6d69ca7dbf01d8a17\" href=\"#6d69ca7dbf01d8a17\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est-ce que les centres de vaccination proposent les deux vaccins ?<\/span><\/a><\/h4><\/div><div id=\"6d69ca7dbf01d8a17\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_6d69ca7dbf01d8a17\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">NON ! Pour des raisons de logistique, tous les centres ne peuvent pas proposer les deux vaccins.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-d509b91ce945ab15c fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_d509b91ce945ab15c\"><a aria-expanded=\"false\" aria-controls=\"d509b91ce945ab15c\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#d509b91ce945ab15c\" href=\"#d509b91ce945ab15c\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Comment faire pour avoir son QR Code ?<\/span><\/a><\/h4><\/div><div id=\"d509b91ce945ab15c\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_d509b91ce945ab15c\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Vous devez d\u2019abord avoir un schema vaccinal complet (voir ici <\/span><a href=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/08\/2021-08-12-schemas-vaccinaux.pdf\"><span style=\"font-weight: 400\">https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/08\/2021-08-12-schemas-vaccinaux.pdf<\/span><\/a><span style=\"font-weight: 400\">)\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Vous pouvez ensuite faire une demande en ligne via ce formulaire : <\/span><a href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/demande-certificat-vaccination\/\"><span style=\"font-weight: 400\">https:\/\/www.service-public.pf\/dsp\/covid-19\/demande-certificat-vaccination\/<\/span><\/a> <\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-bdb309cf160454bd6 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_bdb309cf160454bd6\"><a aria-expanded=\"false\" aria-controls=\"bdb309cf160454bd6\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#bdb309cf160454bd6\" href=\"#bdb309cf160454bd6\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Une personne vaccin\u00e9e peut-\u00eatre porteuse du virus ?<\/span><\/a><\/h4><\/div><div id=\"bdb309cf160454bd6\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_bdb309cf160454bd6\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Oui\u00a0! Cependant la vaccination va lui permettre de se prot\u00e9ger et d\u2019\u00e9viter de d\u00e9velopper la maladie avec des sympt\u00f4mes graves.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-6821eac17a17fc12d fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6821eac17a17fc12d\"><a aria-expanded=\"false\" aria-controls=\"6821eac17a17fc12d\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#6821eac17a17fc12d\" href=\"#6821eac17a17fc12d\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Une personne vaccin\u00e9e peut-\u00eatre contagieuse ?<\/span><\/a><\/h4><\/div><div id=\"6821eac17a17fc12d\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_6821eac17a17fc12d\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Oui\u00a0! Cependant la vaccin<\/span><span style=\"font-weight: 400\">ation peut r\u00e9duire sa charge virale et donc r\u00e9duire ses risques d\u2019\u00eatre contagieuse ou de contaminer son entourage.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-a7a0b732507037b2f fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_a7a0b732507037b2f\"><a aria-expanded=\"false\" aria-controls=\"a7a0b732507037b2f\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#a7a0b732507037b2f\" href=\"#a7a0b732507037b2f\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Une personne vaccin\u00e9e peut-\u00eatre positive ?<\/span><\/a><\/h4><\/div><div id=\"a7a0b732507037b2f\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_a7a0b732507037b2f\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Oui\u00a0! Mais la vaccination diminue fortement le risque de d\u00e9velopper une forme grave de la maladie, d\u2019avoir des sympt\u00f4mes graves.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-a4efd963977af3c4e fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_a4efd963977af3c4e\"><a aria-expanded=\"false\" aria-controls=\"a4efd963977af3c4e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#a4efd963977af3c4e\" href=\"#a4efd963977af3c4e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi une personne vaccin\u00e9e peut tomber malade ou finir \u00e0 l\u2019h\u00f4pital ?<\/span><\/a><\/h4><\/div><div id=\"a4efd963977af3c4e\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_a4efd963977af3c4e\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">I<\/span><span style=\"font-weight: 400\">l n&rsquo;y a pas d&rsquo;efficacit\u00e9 \u00e0 100 %, et chacun peut r\u00e9agir diff\u00e9remment \u00e0 la vaccination comme \u00e0 la maladie. Une personne particuli\u00e8rement fragile (maladies pr\u00e9existantes, comorbidit\u00e9s, \u00e2ge) peut faire une forme grave malgr\u00e9 la vaccination.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Dans la plupart des cas les gens vaccin\u00e9s sont prot\u00e9g\u00e9s des formes graves.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-47dfc26ca62ca406f fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_47dfc26ca62ca406f\"><a aria-expanded=\"false\" aria-controls=\"47dfc26ca62ca406f\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#47dfc26ca62ca406f\" href=\"#47dfc26ca62ca406f\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi une personne vaccin\u00e9e, pouvant transmettre le virus, n\u2019a pas de test RT-PCR impos\u00e9 pour aller dans les \u00eeles ?<\/span><\/a><\/h4><\/div><div id=\"47dfc26ca62ca406f\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_47dfc26ca62ca406f\"><div class=\"panel-body toggle-content fusion-clearfix\"><span style=\"font-weight: 400\">Car une personne vaccin\u00e9e r\u00e9duit sa charge virale en \u00e9tant vaccin\u00e9e et donc r\u00e9duit ses risques d\u2019\u00eatre contagieuse ou de contaminer son entourage.<\/span><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-27be1c2074e6a8df3 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_27be1c2074e6a8df3\"><a aria-expanded=\"false\" aria-controls=\"27be1c2074e6a8df3\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#27be1c2074e6a8df3\" href=\"#27be1c2074e6a8df3\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi est-ce que l\u2019on vaccine en p\u00e9riode d\u2019\u00e9pid\u00e9mie alors que normalement il ne faut pas le faire ?<\/span><\/a><\/h4><\/div><div id=\"27be1c2074e6a8df3\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_27be1c2074e6a8df3\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Nous pouvons tout \u00e0 fait vacciner en p\u00e9riode d&rsquo;\u00e9pid\u00e9mie lorsqu&rsquo;il y a \u00ab\u00a0urgence\u00a0\u00bb\u00a0 \u00e0 le faire. Nous sommes en situation d\u2019urgence.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-501567c4851fc5687 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_501567c4851fc5687\"><a aria-expanded=\"false\" aria-controls=\"501567c4851fc5687\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#501567c4851fc5687\" href=\"#501567c4851fc5687\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Les vaccins Covid-19 conf\u00e8rent-ils une immunit\u00e9 de groupe ou protection collective ?<\/span><\/a><\/h4><\/div><div id=\"501567c4851fc5687\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_501567c4851fc5687\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div id=\"b6bb230bf9b6785d2\" class=\"panel-collapse collapse in\"><strong>OUI.<\/strong> Au moins pour les vaccins ARNm que nous utilisons actuellement, les r\u00e9sultats d&rsquo;\u00e9tudes montrent une diminution de 80 \u00e0 90% du portage du virus (on a le virus, mais on n&rsquo;est pas malade). Autrement dit, nous sommes moins contagieux et le risque de transmettre le virus \u00e0 une autre personne est faible.<\/div>\n<div><\/div>\n<div class=\"panel-collapse collapse in\">Il est fortement probable que les vaccins exercent un effet de groupe si les taux de couverture vaccinale sont suffisants, c&rsquo;est-\u00e0-dire que plus nous sommes vaccin\u00e9s moins le virus peut \u00eatre transmis et donc le virus ne peux plus circuler dans la population.<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-d5f46b68acd41693b fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_d5f46b68acd41693b\"><a aria-expanded=\"false\" aria-controls=\"d5f46b68acd41693b\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#d5f46b68acd41693b\" href=\"#d5f46b68acd41693b\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi on ne rend pas la vaccination obligatoire ?<\/span><\/a><\/h4><\/div><div id=\"d5f46b68acd41693b\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_d5f46b68acd41693b\"><div class=\"panel-body toggle-content fusion-clearfix\"><span style=\"font-weight: 400\">La vaccination est non obligatoire depuis son lancement en Polyn\u00e9sie fran\u00e7aise en janvier 2021. Cependant, une loi de Pays a \u00e9t\u00e9 vot\u00e9e (N\u00b02021-37) le 23 aout 2021 relative \u00e0 l\u2019obligation de vaccination de certaines cat\u00e9gories de personn<\/span><span style=\"font-weight: 400\">es.<\/span><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-7be99b6af80f9ce1b fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_7be99b6af80f9ce1b\"><a aria-expanded=\"false\" aria-controls=\"7be99b6af80f9ce1b\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#7be99b6af80f9ce1b\" href=\"#7be99b6af80f9ce1b\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi vaccine t-on les personnes en bonne sant\u00e9 et les enfants ?<\/span><\/a><\/h4><\/div><div id=\"7be99b6af80f9ce1b\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_7be99b6af80f9ce1b\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Pour limiter la circulation du virus et prot\u00e9ger la collectivit\u00e9 (leur famille entre-autres) et pour limiter le nombre de formes graves et les arr\u00eats de travail afin de pr\u00e9server l&rsquo;\u00e9conomie du pays.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-3968b89959152b5dc fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_3968b89959152b5dc\"><a aria-expanded=\"false\" aria-controls=\"3968b89959152b5dc\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#3968b89959152b5dc\" href=\"#3968b89959152b5dc\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quel est l'impact positif de la vaccination de masse actuelle sur les hospitalisations, sur la r\u00e9animation, et malheureusement sur le nombre de morts ?<\/span><\/a><\/h4><\/div><div id=\"3968b89959152b5dc\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_3968b89959152b5dc\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Sur un million de non vaccin\u00e9s, 132 personnes sont hospitalis\u00e9es et 35 admises en r\u00e9animation. Sur un million de personnes partiellement vaccin\u00e9es, 37 sont hospitalis\u00e9es et huit en r\u00e9animation. Sur un million de personnes compl\u00e8tement vaccin\u00e9es, 16 sont hospitalis\u00e9es et quatre en r\u00e9animation. Conclusion : le vaccin des formes graves.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Voir graphe :<\/span><\/p>\n<div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-4 hover-type-none\"><a href=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-1024x754.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[6d19bebd7734bf63131]\" data-title=\"Admissions Medicales\" title=\"Admissions Medicales\"><img decoding=\"async\" width=\"600\" height=\"442\" src=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-600x442.jpg\" alt class=\"img-responsive wp-image-25069\" srcset=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-200x147.jpg 200w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-400x295.jpg 400w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-600x442.jpg 600w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-800x589.jpg 800w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales-1200x884.jpg 1200w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/09\/admissions-medicales.jpg 1280w\" sizes=\"(max-width: 1100px) 100vw, 1200px\" \/><\/a><\/span><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-b9d0f5ab3b7299b5d fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_b9d0f5ab3b7299b5d\"><a aria-expanded=\"false\" aria-controls=\"b9d0f5ab3b7299b5d\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-5\" data-target=\"#b9d0f5ab3b7299b5d\" href=\"#b9d0f5ab3b7299b5d\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi il n\u2019y a pas de PFIZER dans les Tuamotu ?<\/span><\/a><\/h4><\/div><div id=\"b9d0f5ab3b7299b5d\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_b9d0f5ab3b7299b5d\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Le vaccin PFIZER doit \u00eatre conserv\u00e9 dans des conditions plus compliqu\u00e9es que le vaccin JANSSEN (tr\u00e8s haute temp\u00e9rature, d\u00e9lais de conservation court, etc.)<\/span><\/p>\n<p><span style=\"font-weight: 400\">De plus, le vaccin PFIZER n\u00e9cessite 2 doses, il est donc n\u00e9cessaire de faire d\u00e9placer les \u00e9quipes et la logistique deux fois.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le\u00a0vaccin JANSSEN\u00a0est plus facile \u00e0 conserver et \u00e0 utiliser.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Pour autant ces deux vaccins sont tr\u00e8s efficace pour se prot\u00e9ger de la covid-19.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-11\"><h2 style=\"text-align: center\" data-fontsize=\"28\" data-lineheight=\"42\">PERSONNES CONCERN\u00c9ES<\/h2>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-top:-2%;margin-bottom:3%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#c53466;border-color:#c53466;border-top-width:7px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-5 fusion_builder_column_inner_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:25px;--awb-padding-right:10px;--awb-padding-bottom:25px;--awb-padding-left:10px;--awb-bg-color:rgba(237,237,237,0.5);--awb-bg-color-hover:rgba(237,237,237,0.5);--awb-bg-blend:screen;--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:2px;--awb-icon-size:18px;--awb-content-font-size:18px;--awb-icon-alignment:right;--awb-hover-color:#f9f9f9;--awb-border-color:#c53466;--awb-background-color:#ffffff;--awb-divider-color:#e0dede;--awb-divider-hover-color:#e0dede;--awb-icon-color:#c53466;--awb-title-color:#1d9bac;--awb-content-color:#4a4e57;--awb-icon-box-color:#333333;--awb-toggle-hover-accent-color:#000000;--awb-title-font-family:&quot;Roboto&quot;;--awb-title-font-weight:400;--awb-title-font-style:normal;--awb-content-font-family:&quot;Roboto&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;\"><div class=\"panel-group fusion-toggle-icon-right fusion-toggle-icon-unboxed\" id=\"accordion-24836-6\"><div class=\"fusion-panel panel-default panel-75a6ce68b99a57302 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_75a6ce68b99a57302\"><a aria-expanded=\"false\" aria-controls=\"75a6ce68b99a57302\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-6\" data-target=\"#75a6ce68b99a57302\" href=\"#75a6ce68b99a57302\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Je suis sujet contact d\u2019un cas confirm\u00e9 de covid-19, puis-je me faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"75a6ce68b99a57302\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_75a6ce68b99a57302\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div id=\"b08d42b7099059490\" class=\"panel-collapse collapse in\">\n<div class=\"panel-body toggle-content fusion-clearfix\">Pas dans l\u2019imm\u00e9diat. Je dois avant tout m\u2019isoler pendant 10 jours apr\u00e8s le dernier contact avec le cas positif. Si je ne d\u00e9veloppe pas de sympt\u00f4me durant cette p\u00e9riode, je dois r\u00e9aliser un test PCR de contr\u00f4le avant ma sortie d\u2019isolement. S\u2019il est n\u00e9gatif, je peux alors aller me faire vacciner.<\/div>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-adec797c6f12e2c7a fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_adec797c6f12e2c7a\"><a aria-expanded=\"false\" aria-controls=\"adec797c6f12e2c7a\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-6\" data-target=\"#adec797c6f12e2c7a\" href=\"#adec797c6f12e2c7a\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">J\u2019ai d\u00e9j\u00e0 eu la Covid-19 ou je crois l\u2019avoir eue, puis-je me faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"adec797c6f12e2c7a\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_adec797c6f12e2c7a\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div id=\"b6bb230bf9b6785d2\" class=\"panel-collapse collapse in\">\n<p><strong>Oui, c&rsquo;est possible apr\u00e8s un d\u00e9lai de 2 mois suite \u00e0 mon infection.<\/strong> En r\u00e8gle g\u00e9n\u00e9rale, il n\u2019y a aucune contre-indication \u00e0 vacciner quelqu\u2019un contre une maladie qu\u2019il a d\u00e9j\u00e0 eue.<\/p>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-f30e86da621ba0bb3 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_f30e86da621ba0bb3\"><a aria-expanded=\"false\" aria-controls=\"f30e86da621ba0bb3\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-6\" data-target=\"#f30e86da621ba0bb3\" href=\"#f30e86da621ba0bb3\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00c0 partir de quel \u00e2ge peut-on se faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"f30e86da621ba0bb3\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_f30e86da621ba0bb3\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">\u00c0 partir de l\u2019\u00e2ge de 12 ans avec le vaccin PFIZER et \u00e0 partir de l\u2019\u00e2ge de 18 ans pour le vaccin JANSSEN.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Un\u00a0mineur de 12 \u00e0 15 ans inclus dois venir avec une autorisation e\u0301crite d\u2019un des deux parents ou d\u2019un tuteur le\u0301gal.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Un\u00a0mineur de 16 \u00e0 17 ans inclus\u00a0peux se faire vacciner sans autorisation parentale. La pre\u0301sence de ses parents ou d\u2019un tuteur le\u0301gal est recommande\u0301e mais n\u2019est plus obligatoire.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-9520e790a2cba1c6f fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_9520e790a2cba1c6f\"><a aria-expanded=\"false\" aria-controls=\"9520e790a2cba1c6f\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-6\" data-target=\"#9520e790a2cba1c6f\" href=\"#9520e790a2cba1c6f\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi on ne vaccine pas les enfants de moins de 12 ans ?<\/span><\/a><\/h4><\/div><div id=\"9520e790a2cba1c6f\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_9520e790a2cba1c6f\"><div class=\"panel-body toggle-content fusion-clearfix\"><b>Le vaccin Pfizer permet de vacciner les adolescents \u00e0 partir de 12 ans car il a \u00e9t\u00e9 \u00e9valu\u00e9 \u00e0 partir de cet \u00e2ge.<\/b><\/p>\n<p>Le vaccin Janssen permet de vacciner les personnes \u00e0 partir de 18 ans car il a \u00e9t\u00e9 \u00e9valu\u00e9 \u00e0 partir de cet \u00e2ge. Pour les personnes en dessous de 18 ans, les \u00e9tudes sont encore en cours d\u2019\u00e9valuation de l\u2019efficacit\u00e9 du vaccin.<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-4493895c1cfe6d5de fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_4493895c1cfe6d5de\"><a aria-expanded=\"false\" aria-controls=\"4493895c1cfe6d5de\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-6\" data-target=\"#4493895c1cfe6d5de\" href=\"#4493895c1cfe6d5de\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Puis-je me faire vacciner si je suis enceinte ou si j'allaite mon enfant ? <\/span><\/a><\/h4><\/div><div id=\"4493895c1cfe6d5de\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_4493895c1cfe6d5de\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div><b>Oui, avec le vaccin PFIZER uniquement (pas avec le vaccin JANSSEN), les femmes enceintes d\u00e8s le premier trimestre peuvent se faire vacciner. <\/b>Au d\u00e9part contre-indiqu\u00e9 par mesure de pr\u00e9caution, nous disposons maintenant de donn\u00e9es solides de s\u00e9curit\u00e9 pour pouvoir recommander la vaccination des femmes enceintes. <strong>La vaccination des femmes enceintes est recommand\u00e9e.<\/strong><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-fe93f85e7f3d21204 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_fe93f85e7f3d21204\"><a aria-expanded=\"false\" aria-controls=\"fe93f85e7f3d21204\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-6\" data-target=\"#fe93f85e7f3d21204\" href=\"#fe93f85e7f3d21204\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est-ce qu\u2019on peut se faire vacciner (Primo ou rappel) apr\u00e8s avoir \u00e9t\u00e9 cas contact asymptomatique apr\u00e8s 10 jours ?<\/span><\/a><\/h4><\/div><div id=\"fe93f85e7f3d21204\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_fe93f85e7f3d21204\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">OUI\u00a0! Uniquement si vous n\u2019avez pas eu de sympt\u00f4mes (asymptomatique)<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-801f241bbe8ce1f50 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_801f241bbe8ce1f50\"><a aria-expanded=\"false\" aria-controls=\"801f241bbe8ce1f50\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-6\" data-target=\"#801f241bbe8ce1f50\" href=\"#801f241bbe8ce1f50\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Apr\u00e8s un test RT-PCR ou antig\u00e9nique n\u00e9gatif, peut-on se faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"801f241bbe8ce1f50\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_801f241bbe8ce1f50\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">OUI\u00a0! Un test n\u00e9gatif signifie que vous n\u2019\u00eates pas porteur du virus. Vous pouvez vous donc vous faire vacciner.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-4f1aedaaf0453d222 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_4f1aedaaf0453d222\"><a aria-expanded=\"false\" aria-controls=\"4f1aedaaf0453d222\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-6\" data-target=\"#4f1aedaaf0453d222\" href=\"#4f1aedaaf0453d222\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Apr\u00e8s un test RT-PCR ou antig\u00e9nique n\u00e9gatif, peut-on se faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"4f1aedaaf0453d222\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_4f1aedaaf0453d222\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">OUI\u00a0! Un test n\u00e9gatif signifie que vous n\u2019\u00eates pas porteur du virus. Vous pouvez vous donc vous faire vacciner.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-12\"><h2 style=\"text-align: center\" data-fontsize=\"28\" data-lineheight=\"42\">LES VACCINS<\/h2>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-6 fusion_builder_column_inner_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:25px;--awb-padding-right:10px;--awb-padding-bottom:25px;--awb-padding-left:10px;--awb-bg-color:rgba(237,237,237,0.5);--awb-bg-color-hover:rgba(237,237,237,0.5);--awb-bg-blend:screen;--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:2px;--awb-icon-size:18px;--awb-content-font-size:18px;--awb-icon-alignment:right;--awb-hover-color:#f9f9f9;--awb-border-color:#c53466;--awb-background-color:#ffffff;--awb-divider-color:#e0dede;--awb-divider-hover-color:#e0dede;--awb-icon-color:#c53466;--awb-title-color:#1d9bac;--awb-content-color:#4a4e57;--awb-icon-box-color:#333333;--awb-toggle-hover-accent-color:#000000;--awb-title-font-family:&quot;Roboto&quot;;--awb-title-font-weight:400;--awb-title-font-style:normal;--awb-content-font-family:&quot;Roboto&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;\"><div class=\"panel-group fusion-toggle-icon-right fusion-toggle-icon-unboxed\" id=\"accordion-24836-7\"><div class=\"fusion-panel panel-default panel-d5fa2d4aceb25e92e fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_d5fa2d4aceb25e92e\"><a aria-expanded=\"false\" aria-controls=\"d5fa2d4aceb25e92e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#d5fa2d4aceb25e92e\" href=\"#d5fa2d4aceb25e92e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quels sont les vaccins disponibles contre la Covid-19 et comment fonctionnent-ils ?<\/span><\/a><\/h4><\/div><div id=\"d5fa2d4aceb25e92e\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_d5fa2d4aceb25e92e\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Les vaccins contre la Covid-19 actuellement disponibles en Polyn\u00e9sie sont le <strong>PFIZER et le JANSSEN<\/strong>.<\/p>\n<p>Le virus SARS-Cov-2 responsable de la maladie Covid-19 poss\u00e8de une prot\u00e9ine particuli\u00e8re, la prot\u00e9ine S, qui lui permet d\u2019entrer dans les cellules. Lorsque le virus entre dans l\u2019organisme pour la premi\u00e8re fois, le syst\u00e8me immunitaire d\u00e9tecte la pr\u00e9sence de la prot\u00e9ine S, aussi appel\u00e9e antig\u00e8ne, et commence \u00e0 produire des anticorps. Pendant ce temps le virus se multiplie et provoque la maladie entrainant l\u2019apparition de sympt\u00f4mes.<\/p>\n<p>Le PFIZER est un vaccin dit \u00e0 <strong>\u00ab ARN messager \u00bb ou \u00ab ARNm \u00bb<\/strong>. L\u2019ARNm contenu dans le vaccin est le code qui permet au virus de fabriquer la prot\u00e9ine S. Le vaccin ne contient que ce code, aucune autre partie du virus. Lors de l\u2019injection du vaccin, l\u2019ARNm entre dans nos cellules qui vont elles-m\u00eames fabriquer la prot\u00e9ine S. La prot\u00e9ine S n\u2019est qu\u2019une partie du virus, elle ne rend pas malade. Le syst\u00e8me immunitaire va d\u00e9tecter la prot\u00e9ine S, aussi appel\u00e9e antig\u00e8ne, et produire des anticorps contre cette prot\u00e9ine. Par la suite, lorsque le virus SARS-Cov-2 p\u00e9n\u00e8trera dans l\u2019organisme, il sera imm\u00e9diatement reconnu et neutralis\u00e9 par les anticorps, il ne pourra pas se multiplier, la maladie ne se d\u00e9veloppera pas.<\/p>\n<p>Le JANSSEN est un vaccin dit \u00e0<strong> vecteur viral<\/strong>. Le vaccin est compos\u00e9 d\u2019un virus inoffensif (ad\u00e9novirus 26) qui a \u00e9t\u00e9 modifi\u00e9 pour contenir le g\u00e8ne permettant de fabriquer la prot\u00e9ine de pointe S du SARS-CoV-2. Le syst\u00e8me immunitaire de la personne reconna\u00eet la prot\u00e9ine S comme \u00e9trang\u00e8re et produira des anticorps neutralisants et autres.<\/p>\n<p>Les vaccins \u00e0 ARNm et les vaccins reposant sur des vecteurs viraux ne contiennent pas d\u2019adjuvant, leur structure m\u00eame permettant de stimuler le syst\u00e8me immunitaire inn\u00e9.<\/p>\n<p>Les vaccins qui n\u00e9cessitent l\u2019utilisation d\u2019adjuvant sont les vaccins inactiv\u00e9s et les vaccins prot\u00e9iques.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-0c5525968b8b58c6c fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_0c5525968b8b58c6c\"><a aria-expanded=\"false\" aria-controls=\"0c5525968b8b58c6c\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#0c5525968b8b58c6c\" href=\"#0c5525968b8b58c6c\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi autant de vaccins ?<\/span><\/a><\/h4><\/div><div id=\"0c5525968b8b58c6c\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_0c5525968b8b58c6c\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">De nombreux laboratoires ont \u00e9t\u00e9 solicit\u00e9s pour d\u00e9velopper un vaccin contre la covid-19. Plusieurs vaccins utilisant des techniques diff\u00e9rentes ont ainsi \u00e9t\u00e9 d\u00e9velopp\u00e9s (PFIZER, MODERNA, JANSSEN, ASTRAZENECA, etc).<\/span><\/p>\n<p><span style=\"font-weight: 400\">En Polyn\u00e9sie, seuls les vaccins PFIZER et JANSSEN sont propos\u00e9s.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-d99df951dacb4fd06 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_d99df951dacb4fd06\"><a aria-expanded=\"false\" aria-controls=\"d99df951dacb4fd06\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#d99df951dacb4fd06\" href=\"#d99df951dacb4fd06\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quelle est la composition des vaccins PFIZER et JANSSEN ?<\/span><\/a><\/h4><\/div><div id=\"d99df951dacb4fd06\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_d99df951dacb4fd06\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><strong> Pfizer :<\/strong><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Antig\u00e8ne<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">ARNm COVID-19 (incorpor\u00e9 dans des nanoparticules lipidiques) : 30 microgrammes. <\/span><span style=\"font-weight: 400\">Il s&rsquo;agit de mol\u00e9cules d&rsquo;acide ribonucl\u00e9ique (ARN) messager (ARNm) produit \u00e0 l&rsquo;aide d&rsquo;une transcription <\/span><i><span style=\"font-weight: 400\">in vitro<\/span><\/i><span style=\"font-weight: 400\"> sans cellule \u00e0 partir des matrices d&rsquo;ADN correspondantes, qui codent la prot\u00e9ine virale de spicule (appel\u00e9e prot\u00e9ine Spike ou prot\u00e9ine S) du coronavirus SARS-CoV-2 responsable de la covid 19.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Excipients\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Lipides<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">ALC-0315<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">ALC-0159 Le composant ALC-0159 contient des mol\u00e9cules de poly\u00e9thyl\u00e8ne glycol (PEG). Ces mol\u00e9cules, \u00e9galement pr\u00e9sentes dans des produits cosm\u00e9tiques et m\u00e9dicaments, pourraient \u00eatre \u00e0 l&rsquo;origine des rares cas d&rsquo;anaphylaxie (r\u00e9action allergique grave) qui ont \u00e9t\u00e9 rapport\u00e9s (fr\u00e9quence d&rsquo;environ un cas pour 100 000 vaccinations).<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">1,2- dist\u00e9aroyl-sn-glyc\u00e9ro-3-phosphocholine (DSPC)<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Cholest\u00e9rol<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Autres composants<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Chlorure de sodium<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Chlorure de potassium<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Phosphate monopotassique<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Phosphate disodique dihydrat\u00e9<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Saccharose<\/span><\/li>\n<\/ul>\n<p><strong>JANSSEN :<\/strong><\/p>\n<p><span style=\"font-weight: 400\">Le vaccin consiste en un vecteur ad\u00e9noviral recombinant<\/span><span style=\"font-weight: 400\"> de type 26 (Ad26.COV2-S) incapable de se r\u00e9pliquer et exprimant la glycoprot\u00e9ine Spike* (encore appel\u00e9e prot\u00e9ine S ou prot\u00e9ine de spicule) du coronavirus SARS-CoV-2.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">* : produit dans la lign\u00e9e cellulaire PER.C6 TetR et par la technologie de l&rsquo;ADN recombinant.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Une dose (0,5 mL) contient :<\/span><\/p>\n<ol>\n<li><b> Antig\u00e8ne<\/b><\/li>\n<\/ol>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">au moins de 8,92 log10 unit\u00e9s infectieuses (U.I.)<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Le produit contient des organismes g\u00e9n\u00e9tiquement modifi\u00e9s (OGM).<\/span><\/p>\n<ol start=\"2\">\n<li><b> Excipients<\/b><\/li>\n<\/ol>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Acide citrique monohydrat\u00e9<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Citrate trisodique dihydrat\u00e9 (uniquement pour les pr\u00e9sentations en bo\u00eete de 10 flacons)<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">\u00c9thanol (environ 2 mg par dose, soit une quantit\u00e9 faible sans effets notables)<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">2-hydroxypropyl-\u03b2-cyclodextrine (HBCD)<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Polysorbate 80<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Chlorure de sodium (moins de 1 mmol de sodium par dose de 0,5 mL, soit 23 mg, c&rsquo;est-\u00e0-dire qu&rsquo;il peut \u00eatre consid\u00e9r\u00e9 comme \u00e9tant \u00ab\u00a0sans sodium\u00a0\u00bb)<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Hydroxyde de sodium<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Acide chlorhydrique<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-6ac85bb319ca839e3 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6ac85bb319ca839e3\"><a aria-expanded=\"false\" aria-controls=\"6ac85bb319ca839e3\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#6ac85bb319ca839e3\" href=\"#6ac85bb319ca839e3\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Une dose de vaccin est-elle suffisante ?<\/span><\/a><\/h4><\/div><div id=\"6ac85bb319ca839e3\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_6ac85bb319ca839e3\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<div>\n<div><strong>Pour le Vaccin PFIZER, NON<\/strong>.\u00a0Quand le sch\u00e9ma de vaccination doit s\u2019effectuer en deux doses, il est recommand\u00e9 de faire les deux doses en respectant l\u2019intervalle de temps recommand\u00e9 entre les deux. En effet, c\u2019est apr\u00e8s deux injections que l\u2019on obtient la plus grande efficacit\u00e9. Aussi, apr\u00e8s deux doses, l\u2019immunog\u00e9nicit\u00e9, c\u2019est-\u00e0-dire notre capacit\u00e9 \u00e0 r\u00e9agir face au virus s\u2019il venait \u00e0 nous infecter par la suite, serait 10 \u00e0 100 fois sup\u00e9rieure, offrant une protection plus prolong\u00e9e dans le temps.<\/div>\n<\/div>\n<div><\/div>\n<div><strong>Pour le Vaccin Janssen, OUI<\/strong>. Le sch\u00e9ma de vaccination s\u2019effectue en une seule dose. Une seule dose est n\u00e9cessaire pour obtenir la plus grande efficacit\u00e9.<\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-27c0546c730d41aed fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_27c0546c730d41aed\"><a aria-expanded=\"false\" aria-controls=\"27c0546c730d41aed\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#27c0546c730d41aed\" href=\"#27c0546c730d41aed\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quels sont les effets secondaires\/ind\u00e9sirables du vaccin ?<\/span><\/a><\/h4><\/div><div id=\"27c0546c730d41aed\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_27c0546c730d41aed\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Comme tous les m\u00e9dicaments, les vaccins peuvent entra\u00eener des effets ind\u00e9sirables.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ils sont classiques, relativement fr\u00e9quents et communs \u00e0 tous les vaccins : douleur au point d\u2019injection, fatigue, maux de t\u00eate, douleurs musculaires ou articulaires, frissons ou fi\u00e8vre.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ces\u00a0effets secondaires\/ind\u00e9sirables\u00a0montrent que votre syst\u00e8me immunitaire est en train de r\u00e9agir pour se d\u00e9fendre contre l\u2019antig\u00e8ne.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ils sont souvent l\u00e9gers et ne durent que quelques jours.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Si des effets deviennent g\u00eanants ou\u00a0importants, il faut le signaler \u00e0 son m\u00e9decin traitant qui d\u00e9clarera la situation si n\u00e9c\u00e9ssaire \u00e0 l\u2019ARASS (Agence de r\u00e9gulation de l&rsquo;action sanitaire et sociale).<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-933ce2e0fc1e34d20 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_933ce2e0fc1e34d20\"><a aria-expanded=\"false\" aria-controls=\"933ce2e0fc1e34d20\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#933ce2e0fc1e34d20\" href=\"#933ce2e0fc1e34d20\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Les mutations du virus peuvent-elles rendre le vaccin inefficace ?<\/span><\/a><\/h4><\/div><div id=\"933ce2e0fc1e34d20\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_933ce2e0fc1e34d20\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>C\u2019est possible mais peu probable. Le SARS-Cov-2 mute r\u00e9guli\u00e8rement comme tous les virus, mais aucune mutation d\u00e9tect\u00e9e \u00e0 ce jour n\u2019a affect\u00e9 la prot\u00e9ine S (sur laquelle est bas\u00e9e le vaccin) au point d\u2019alt\u00e9rer la capacit\u00e9 du corps humain \u00e0 la reconna\u00eetre. Les mutations du SARS-Cov-2 sont surveill\u00e9es de tr\u00e8s pr\u00e8s par les scientifiques, qui travailleront \u00e0 l\u2019adaptation du vaccin en cas de mutation importante.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-89fda2e0ff01ed1da fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_89fda2e0ff01ed1da\"><a aria-expanded=\"false\" aria-controls=\"89fda2e0ff01ed1da\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#89fda2e0ff01ed1da\" href=\"#89fda2e0ff01ed1da\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Les vaccins utilis\u00e9s sont-ils s\u00fbrs ?<\/span><\/a><\/h4><\/div><div id=\"89fda2e0ff01ed1da\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_89fda2e0ff01ed1da\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Tous les vaccins autoris\u00e9s en Polyn\u00e9sie fran\u00e7aise font l\u2019objet d\u2019un contr\u00f4le rigoureux pour s\u2019assurer de leur efficacit\u00e9 et de leur s\u00fbret\u00e9. De plus, une fois disponible sur le Fenua, nous continuerons \u00e0 les surveiller afin de s\u2019assurer de leur suret\u00e9.<\/p>\n<p>Pour en savoir plus sur la surveillance de ces vaccins en pratique, consulter le site de l\u2019ARASS\u00a0\u00bb avec le lien suivant\u00a0:\u00a0<a href=\"https:\/\/www.service-public.pf\/arass\/pharmacovigilance-des-vaccins-contre-la-covid-19\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.service-public.pf\/arass\/pharmacovigilance-des-vaccins-contre-la-covid-19\/&amp;source=gmail&amp;ust=1611088412047000&amp;usg=AFQjCNE-j5ImLLzKl-UCnN1rfNtk-cdVUw\">https:\/\/www.service-public.pf\/arass\/pharmacovigilance-des-vaccins-contre-la-covid-19\/<\/a><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-05efd75df4ce4a707 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_05efd75df4ce4a707\"><a aria-expanded=\"false\" aria-controls=\"05efd75df4ce4a707\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#05efd75df4ce4a707\" href=\"#05efd75df4ce4a707\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Les vaccins \u00e0 ARN sont nouveaux mais sont-ils s\u00fbr ?<\/span><\/a><\/h4><\/div><div id=\"05efd75df4ce4a707\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_05efd75df4ce4a707\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Aucun vaccin \u00e0 ARN n\u2019avait \u00e9t\u00e9 homologu\u00e9 avant le vaccin contre la Covid-19, mais ces vaccins font l\u2019objet d\u2019\u00e9tudes depuis une vingtaine d\u2019ann\u00e9es et plusieurs essais cliniques y compris chez l\u2019humain avaient d\u00e9j\u00e0 \u00e9t\u00e9 men\u00e9s.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-6ba789b635c87e899 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6ba789b635c87e899\"><a aria-expanded=\"false\" aria-controls=\"6ba789b635c87e899\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#6ba789b635c87e899\" href=\"#6ba789b635c87e899\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est-ce que je peux avoir les deux vaccins pour \u00eatre encore plus prot\u00e9g\u00e9 ?<\/span><\/a><\/h4><\/div><div id=\"6ba789b635c87e899\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_6ba789b635c87e899\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Le Vaccin PFIZER et le vaccin JANSSEN sont les seuls propos\u00e9s en Polyn\u00e9sie.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Vous pouvez donc choisir entre l\u2019un et l\u2019autre, mais pas les deux.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Il est possible qu\u2019un rappel soit recommand\u00e9 prochainement pour une meilleure protection, mais cela sera confirm\u00e9 ult\u00e9rieurement.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-be64218580a83f7d7 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_be64218580a83f7d7\"><a aria-expanded=\"false\" aria-controls=\"be64218580a83f7d7\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#be64218580a83f7d7\" href=\"#be64218580a83f7d7\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Le vaccin (PFIZER ou JANSSEN) met combien de temps pour agir ?<\/span><\/a><\/h4><\/div><div id=\"be64218580a83f7d7\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_be64218580a83f7d7\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Le Vaccin PFIZER est efficace \u00e0 95%, 7 jours apr\u00e8s la deuxi\u00e8me dose.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le Vaccin JANSSEN est efficace \u00e0 68%, 14 jours apr\u00e8s la seule et unique dose.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-65e230d0f48931b7a fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_65e230d0f48931b7a\"><a aria-expanded=\"false\" aria-controls=\"65e230d0f48931b7a\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#65e230d0f48931b7a\" href=\"#65e230d0f48931b7a\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quelles sont les contre-indications de la vaccination ?<\/span><\/a><\/h4><\/div><div id=\"65e230d0f48931b7a\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_65e230d0f48931b7a\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Un ant\u00e9c\u00e9dent de<\/span><a href=\"https:\/\/www.mesvaccins.net\/textes\/20210611_cosv_covid_vacc_enfants_PIMS.pdf\"> <span style=\"font-weight: 400\">syndrome inflammatoire multi-syst\u00e9mique p\u00e9diatrique<\/span><\/a><span style=\"font-weight: 400\"> (PIMS), une complication extr\u00eamement rare qui a atteint certains enfants et adolescents \u00e0 la suite d&rsquo;une infection par le SARS-CoV-2.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Un ant\u00e9c\u00e9dent de myocardite, de p\u00e9ricardite ou d&rsquo;h\u00e9patite grave ayant n\u00e9cessit\u00e9 une hospitalisation et faisant suite \u00e0 une premi\u00e8re injection de vaccin d&rsquo;ARNm.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Une allergie \u00e0 l&rsquo;un des composants du vaccin, le PEG 2000 ou poly\u00e9thyl\u00e8ne glycol, une situation qui concernerait \u00e0 peu pr\u00e8s 10 cas en France selon le ministre de la Sant\u00e9.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Une allergie de type anaphylactique \u00e0 un composant du vaccin ou une r\u00e9action anaphylactique survenue apr\u00e8s une premi\u00e8re dose de vaccin.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Le vaccin<\/span><a href=\"https:\/\/www.mesvaccins.net\/web\/vaccines\/650-vaxzevria-covid-19-vaccine-astrazeneca\"> <span style=\"font-weight: 400\">Vaxzevria<\/span><\/a><span style=\"font-weight: 400\"> (AstraZeneca) est sp\u00e9cifiquement contre-indiqu\u00e9 chez les personnes qui ont pr\u00e9sent\u00e9 un syndrome thrombotique thrombocytop\u00e9nique (STT) suite \u00e0 la vaccination par Vaxzevria et chez des personnes ayant d\u00e9j\u00e0 pr\u00e9sent\u00e9 des \u00e9pisodes de syndrome de fuite capillaire.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Le vaccin<\/span><a href=\"https:\/\/www.mesvaccins.net\/web\/vaccines\/666-janssen-covid-19-vaccine#vaccin_contre-indications\"> <span style=\"font-weight: 400\">Janssen COVID-19 Vaccine<\/span><\/a><span style=\"font-weight: 400\"> est contre-indiqu\u00e9 chez les personnes ayant pr\u00e9sent\u00e9 des \u00e9pisodes de syndrome de fuite capillaire.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Ni la grossesse, ni un \u00ab ant\u00e9c\u00e9dent d&rsquo;allergie \u00e0 un antibiotique ou une piq\u00fbre d&rsquo;abeille \u00bb ne constituent des contre-indications \u00e0 la vaccination.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-2efb3b48eaafce7fc fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_2efb3b48eaafce7fc\"><a aria-expanded=\"false\" aria-controls=\"2efb3b48eaafce7fc\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#2efb3b48eaafce7fc\" href=\"#2efb3b48eaafce7fc\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi apr\u00e8s avoir eu la covid-19, les anticorps ne sont pas suffisants et on doit donc se faire vacciner ?<\/span><\/a><\/h4><\/div><div id=\"2efb3b48eaafce7fc\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_2efb3b48eaafce7fc\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Les anticorps sont suffisants, mais on ne sait pas pendant combien de temps. La vaccination agit comme un rappel permettant de prolonger la dur\u00e9e de l\u2019immunit\u00e9, et de la renforcer.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-d3d2bca1d23ef6cb6 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_d3d2bca1d23ef6cb6\"><a aria-expanded=\"false\" aria-controls=\"d3d2bca1d23ef6cb6\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-7\" data-target=\"#d3d2bca1d23ef6cb6\" href=\"#d3d2bca1d23ef6cb6\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Doit-on recevoir une deuxi\u00e8me dose (Vaccin PFIZER) apr\u00e8s avoir \u00e9t\u00e9 positif \u00e0 la covid-19 ? Si oui, combien de temps apr\u00e8s ?<\/span><\/a><\/h4><\/div><div id=\"d3d2bca1d23ef6cb6\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_d3d2bca1d23ef6cb6\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">OUI\u00a0! Il faut attendre 2 \u00e0 6 mois pour recevoir votre deuxi\u00e8me dose \u00e0 partir du jour de pr\u00e9l\u00e8vement positif.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-top:-2%;margin-bottom:3%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#c53466;border-color:#c53466;border-top-width:7px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-13\"><h2 style=\"text-align: center\" data-fontsize=\"28\" data-lineheight=\"42\">ID\u00c9ES RE\u00c7UES ET D\u00c9SINFORMATION<\/h2>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-top:-2%;margin-bottom:3%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#c53466;border-color:#c53466;border-top-width:7px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-7 fusion_builder_column_inner_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:25px;--awb-padding-right:10px;--awb-padding-bottom:25px;--awb-padding-left:10px;--awb-bg-color:rgba(237,237,237,0.5);--awb-bg-color-hover:rgba(237,237,237,0.5);--awb-bg-blend:screen;--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:2px;--awb-icon-size:18px;--awb-content-font-size:18px;--awb-icon-alignment:right;--awb-hover-color:#f9f9f9;--awb-border-color:#c53466;--awb-background-color:#ffffff;--awb-divider-color:#e0dede;--awb-divider-hover-color:#e0dede;--awb-icon-color:#c53466;--awb-title-color:#1d9bac;--awb-content-color:#4a4e57;--awb-icon-box-color:#333333;--awb-toggle-hover-accent-color:#000000;--awb-title-font-family:&quot;Roboto&quot;;--awb-title-font-weight:400;--awb-title-font-style:normal;--awb-content-font-family:&quot;Roboto&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;\"><div class=\"panel-group fusion-toggle-icon-right fusion-toggle-icon-unboxed\" id=\"accordion-24836-8\"><div class=\"fusion-panel panel-default panel-f417403b29772a537 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_f417403b29772a537\"><a aria-expanded=\"false\" aria-controls=\"f417403b29772a537\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-8\" data-target=\"#f417403b29772a537\" href=\"#f417403b29772a537\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Le virus SARS-Cov-2 a-t-il pu \u00eatre fabriqu\u00e9 artificiellement dans un laboratoire ?<\/span><\/a><\/h4><\/div><div id=\"f417403b29772a537\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_f417403b29772a537\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Non. Les \u00e9tudes g\u00e9n\u00e9tiques sur le virus permettent de retracer son histoire. Elles d\u00e9montrent irr\u00e9futablement que le virus n\u2019a pas \u00e9t\u00e9 fabriqu\u00e9 par manipulation dans un laboratoire.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-30c789a4ec2813566 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_30c789a4ec2813566\"><a aria-expanded=\"false\" aria-controls=\"30c789a4ec2813566\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-8\" data-target=\"#30c789a4ec2813566\" href=\"#30c789a4ec2813566\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Y-a-t-il des adjuvants, m\u00e9taux lourds ou de l\u2019aluminium dans les vaccins utilis\u00e9s ?<\/span><\/a><\/h4><\/div><div id=\"30c789a4ec2813566\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_30c789a4ec2813566\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><strong>Non.<\/strong> Il n\u2019y a ni adjuvant, ni m\u00e9taux lourds, ni d\u2019aluminium dans les vaccins utilis\u00e9s actuellement.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-2010af57181e57e20 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_2010af57181e57e20\"><a aria-expanded=\"false\" aria-controls=\"2010af57181e57e20\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-8\" data-target=\"#2010af57181e57e20\" href=\"#2010af57181e57e20\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est-ce que le vaccin \u00e0 ARN messager (PFIZER) peut modifier l\u2019ADN ?<\/span><\/a><\/h4><\/div><div id=\"2010af57181e57e20\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_2010af57181e57e20\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Non !<\/span><span style=\"font-weight: 400\">\u00a0Lors de l\u2019expression des g\u00e8nes, l\u2019information circule uniquement dans le sens ADN \u00e0 ARN. Par ailleurs, il n\u2019est pas non plus possible que le contenu des vaccins \u00e0 ARNm entre dans le noyau de nos cellules o\u00f9 se trouve notre ADN. L&rsquo;ARNm vient de l&rsquo;ADN mais n&rsquo;y retourne pas !<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-f44520c6a766a1e63 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_f44520c6a766a1e63\"><a aria-expanded=\"false\" aria-controls=\"f44520c6a766a1e63\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-8\" data-target=\"#f44520c6a766a1e63\" href=\"#f44520c6a766a1e63\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\"> Est-ce qu\u2019il y a des nanoparticules 5G dans les vaccins PFIZER et JANSSEN ?<\/span><\/a><\/h4><\/div><div id=\"f44520c6a766a1e63\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_f44520c6a766a1e63\"><div class=\"panel-body toggle-content fusion-clearfix\"><span style=\"font-weight: 400\">NON !\u00a0Ceci est une FAKE NEWS !<\/span><\/p>\n<p><span style=\"font-weight: 400\">Il s\u2019agit de nanoparticules lipidiques (voir la composition du vaccin).<\/span><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-ff3998a4e28af4fd2 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_ff3998a4e28af4fd2\"><a aria-expanded=\"false\" aria-controls=\"ff3998a4e28af4fd2\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-8\" data-target=\"#ff3998a4e28af4fd2\" href=\"#ff3998a4e28af4fd2\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Comment un vaccin peut-il \u00eatre d\u00e9velopp\u00e9 si rapidement ? Pourquoi ce n\u2019est pas le cas pour des maladies connues comme le VIH, le Cancer, etc ?<\/span><\/a><\/h4><\/div><div id=\"ff3998a4e28af4fd2\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_ff3998a4e28af4fd2\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Parce que tous les laboratoires se sont saisis du probl\u00e8me Covid-19, que les moyens (humains et financiers) ont \u00e9t\u00e9 mis \u00e0 disposition des chercheurs et que tous les laboratoires ont collabor\u00e9 ensemble. D&rsquo;autre part,\u00a0 la technique de l&rsquo;A<\/span><span style=\"font-weight: 400\">RN <\/span><span style=\"font-weight: 400\">messager est utilis\u00e9e depuis plus de 40 ans, elle est aujourd\u2019hui ma\u00eetris\u00e9e et la technique plus classique des vaccins \u00e0 vecteur viral (Janssen) est aussi tr\u00e8s connue et ma\u00eetris\u00e9e.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-dabed2c9a0ac57242 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_dabed2c9a0ac57242\"><a aria-expanded=\"false\" aria-controls=\"dabed2c9a0ac57242\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-8\" data-target=\"#dabed2c9a0ac57242\" href=\"#dabed2c9a0ac57242\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Est-ce que le vaccin rend magn\u00e9tique ? Comme la pi\u00e8ce ou le t\u00e9l\u00e9phone qui colle sur le bras.<\/span><\/a><\/h4><\/div><div id=\"dabed2c9a0ac57242\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_dabed2c9a0ac57242\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">NON ! Ceci est une fake News !<\/span><\/p>\n<p><span style=\"font-weight: 400\">La composition des vaccins ne pr\u00e9sente aucun composant magn\u00e9tique.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le fait d\u2019avoir un objet qui peut coller sur la peau s\u2019explique par (dans certains cas) la tenue en s\u00e9bum de votre peau.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Plus la peau sera grasse, plus les objets \u00e0 face plate pourront coller.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Aussi, une r\u00e9action inflammatoire peut se produit sur le point d\u2019injection du vaccin, donnant une peau plus chaude et donc plus encline \u00e0 ces ph\u00e9nom\u00e8nes de ventouse.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-ff0d1af66344548a6 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_ff0d1af66344548a6\"><a aria-expanded=\"false\" aria-controls=\"ff0d1af66344548a6\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-8\" data-target=\"#ff0d1af66344548a6\" href=\"#ff0d1af66344548a6\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Le vaccin est toujours en phase de test ! Nous sommes des cobayes !?<\/span><\/a><\/h4><\/div><div id=\"ff0d1af66344548a6\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_ff0d1af66344548a6\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Les vaccins contre la Covid ont tous \u00e9t\u00e9 test\u00e9s.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Cela fait bien longtemps que la phase de test est termin\u00e9e.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Les tests ont largement prouv\u00e9 leur efficacit\u00e9 et leur innocuit\u00e9.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-061afc0362bb06e22 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_061afc0362bb06e22\"><a aria-expanded=\"false\" aria-controls=\"061afc0362bb06e22\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-8\" data-target=\"#061afc0362bb06e22\" href=\"#061afc0362bb06e22\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Le vaccin peut rendre infertile ?<\/span><\/a><\/h4><\/div><div id=\"061afc0362bb06e22\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_061afc0362bb06e22\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">NON ! De nombreux essais complets ont \u00e9t\u00e9 r\u00e9alis\u00e9s sp\u00e9cifiquement sur des femmes enceintes pour la vaccination.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Aucun effet n\u00e9faste n\u2019a \u00e9t\u00e9 enregistr\u00e9 pour la m\u00e8re ou pour le foetus.<\/span><\/p>\n<p><span style=\"font-weight: 400\">C\u2019est \u00e9galement le cas chez les hommes pour qui la qualit\u00e9 du sperme n\u2019a connu aucune diff\u00e9rence avant et apr\u00e8s le vaccin.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-d81663bada1a1ee29 fusion-toggle-no-divider fusion-toggle-boxed-mode\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_d81663bada1a1ee29\"><a aria-expanded=\"false\" aria-controls=\"d81663bada1a1ee29\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-24836-8\" data-target=\"#d81663bada1a1ee29\" href=\"#d81663bada1a1ee29\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Pourquoi dit-on que les laboratoires sont d\u00e9charg\u00e9s de leur responsabilit\u00e9s ?<\/span><\/a><\/h4><\/div><div id=\"d81663bada1a1ee29\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_d81663bada1a1ee29\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><span style=\"font-weight: 400\">Ceci est une fausse rumeur ! En cas d\u2019effet ind\u00e9sirable grave, le laboratoire concern\u00e9 sera tenu responsable \u00e0 condition de prouver le lien de cause \u00e0 effet du vaccin et de l\u2019effet ind\u00e9sirables. (Ex: avoir un probl\u00e8me au genoux en tombant et d\u00e9noncer le vaccin).<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le laboratoire lui, doit apporter la preuve qu\u2019il a tout \u00e0 fait pour \u00e9viter cet effets ind\u00e9sirables grave, conform\u00e9ment \u00e0 la r\u00e9glementation europ\u00e9enne.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Non, le laboratoire n\u2019est pas d\u00e9charg\u00e9 de sa responsabilit\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Oui, le victime peut \u00eatre indemnis\u00e9 le cas \u00e9chant.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:900px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-5 hover-type-none\"><img decoding=\"async\" width=\"1989\" height=\"478\" title=\"Gestes Barrieres Vaccin\" src=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin.png\" alt class=\"img-responsive wp-image-18507\" srcset=\"https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin-200x48.png 200w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin-400x96.png 400w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin-600x144.png 600w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin-800x192.png 800w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin-1200x288.png 1200w, https:\/\/www.service-public.pf\/dsp\/wp-content\/uploads\/sites\/12\/2021\/01\/gestes-barrieres-vaccin.png 1989w\" sizes=\"(max-width: 1100px) 100vw, 1200px\" \/><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-14\"><p><u><strong><a href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/professionnels-sante-covid-19\/\">Vous \u00eates professionnel de sant\u00e9, consultez la documentation sur la vaccination COVID-19, en cliquant sur ce lien.<\/a><\/strong><\/u><\/p>\n<\/div><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-1 content-boxes-icon-on-side content-left\" style=\"--awb-backgroundcolor:#a3ce80;--awb-body-color:#000000;--awb-title-color:#ffffff;--awb-margin-bottom:30px;--awb-hover-accent-color:#3697c3;--awb-circle-hover-accent-color:#3697c3;--awb-item-margin-bottom:40px;\" data-animationOffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:#b22992;--awb-content-padding-left:94px;\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper-background link-area-link-icon icon-hover-animation-pulsate\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div class=\"icon\"><i style=\"border-color:#333333;border-width:0px;background-color:#333333;box-sizing:content-box;height:74px;width:74px;line-height:74px;border-radius:50%;font-size:37px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-phone-square fas circle-yes\"><\/i><\/div><h3 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h3_typography-font-size:25px;--fontSize:25;line-height:1.5;padding-left:94px;\">Pour toutes questions sur la vaccination COVID-19<\/h3><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\">\n<p>Contactez le 40 455 000 ou envoyer un mail \u00e0 renseignements.covid19@sante.gov.pf<\/p>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-no-large-visibility\" style=\"--awb-padding-right:10px;--awb-padding-left:10px;--awb-bg-color:#f7f7f7;--awb-bg-color-hover:#f7f7f7;--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-text fusion-text-15\"><h3 style=\"text-align: center\" data-fontsize=\"22\" data-lineheight=\"33\">PLUS D&rsquo;INFORMATIONS<\/h3>\n<div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-no-small-visibility fusion-no-medium-visibility\" style=\"margin-left: auto;margin-right: auto;margin-top:2%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#3abfbf;border-color:#3abfbf;border-top-width:5px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-9 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Coronavirus COVID-19<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-10 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/cas-confirmes\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">JE SUIS UN CAS CONFIRM\u00c9<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-11 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/sujets-contact-covid\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">JE SUIS UN SUJET CONTACT<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-12 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/espace-grand-public-covid\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Espace Grand Public<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-13 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/professionnels-sante-covid-19\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Espace professionnels de sant\u00e9<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-14 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/espace-entreprise-covid\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">ESPACE ENTREPRISES<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-15 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/espace-voyageurs\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">ESPACE VOYAGEURS<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-16 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/espace-commune\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">ESPACE COMMUNE<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-align-block\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-17 fusion-button-span-yes \" style=\"--button_bevel_color:#ffc64b;--button_accent_color:#ffffff;--button_border_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#105378;--button_border_width-top:0px;--button_border_width-right:0px;--button_border_width-bottom:0px;--button_border_width-left:0px;--button-border-radius-top-left:2px;--button-border-radius-top-right:2px;--button-border-radius-bottom-right:2px;--button-border-radius-bottom-left:2px;--button_gradient_top_color:#3bafbf;--button_gradient_bottom_color:#3bafbf;--button_gradient_top_color_hover:#037f90;--button_gradient_bottom_color_hover:#037f90;\" target=\"_self\" href=\"https:\/\/www.service-public.pf\/dsp\/covid-19\/questions-frequentes\/\" id=\"bouton-bleu\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Questions fr\u00e9quentes<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:2%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-16\"><h3 style=\"text-align: center\" data-fontsize=\"22\" data-lineheight=\"33\">SUIVEZ-NOUS<\/h3>\n<div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-no-small-visibility fusion-no-medium-visibility\" style=\"margin-left: auto;margin-right: auto;margin-top:-5%;margin-bottom:4%;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#3abfbf;border-color:#3abfbf;border-top-width:5px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div>\n<\/div><div class=\"fusion-widget-area awb-widget-area-element fusion-widget-area-2 fusion-content-widget-area\" style=\"--awb-title-color:#333333;--awb-padding:0px 0px 0px 0px;\">\n\t\t<section id=\"recent-posts-7\" class=\"widget widget_recent_entries\">\n\t\t<div class=\"heading\"><h4 class=\"widget-title\">Articles r\u00e9cents<\/h4><\/div>\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.service-public.pf\/dsp\/2026\/05\/12\/bulletin-de-surveillance-sanitaire-de-la-s18-2026\/\">Bulletin de Surveillance Sanitaire de la S18 2026<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.service-public.pf\/dsp\/2026\/05\/04\/bulletin-de-surveillance-sanitaire-de-la-s17-2026\/\">Bulletin de Surveillance Sanitaire de la S17 2026<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.service-public.pf\/dsp\/2026\/04\/27\/bulletin-de-surveillance-sanitaire-de-la-s16-2026\/\">Bulletin de Surveillance Sanitaire de la S16 2026<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.service-public.pf\/dsp\/2026\/04\/20\/bulletin-de-surveillance-sanitaire-de-la-s15-2026\/\">Bulletin de Surveillance Sanitaire de la S15 2026<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.service-public.pf\/dsp\/2026\/04\/13\/bulletin-de-surveillance-sanitaire-de-la-s14-2026\/\">Bulletin de Surveillance Sanitaire de la S14 2026<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t<\/section><div class=\"fusion-additional-widget-content\"><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":182,"featured_media":18578,"parent":12407,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"Toutes les informations sur la vaccination COVID-19 en Polyn\u00e9sie fran\u00e7aise","_seopress_robots_index":"","footnotes":""},"class_list":["post-24836","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.service-public.pf\/dsp\/wp-json\/wp\/v2\/pages\/24836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.service-public.pf\/dsp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.service-public.pf\/dsp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dsp\/wp-json\/wp\/v2\/users\/182"}],"replies":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dsp\/wp-json\/wp\/v2\/comments?post=24836"}],"version-history":[{"count":0,"href":"https:\/\/www.service-public.pf\/dsp\/wp-json\/wp\/v2\/pages\/24836\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dsp\/wp-json\/wp\/v2\/pages\/12407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dsp\/wp-json\/wp\/v2\/media\/18578"}],"wp:attachment":[{"href":"https:\/\/www.service-public.pf\/dsp\/wp-json\/wp\/v2\/media?parent=24836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}