{"id":7765,"date":"2022-09-14T09:22:41","date_gmt":"2022-09-14T19:22:41","guid":{"rendered":"https:\/\/www.fonction-publique.gov.pf\/?p=7765"},"modified":"2022-09-14T09:22:41","modified_gmt":"2022-09-14T19:22:41","slug":"examen-professionnel-epreuves-dadmissibilite","status":"publish","type":"post","link":"https:\/\/www.service-public.pf\/dti\/2022\/09\/14\/examen-professionnel-epreuves-dadmissibilite\/","title":{"rendered":"Examen professionnel &#8211; \u00c9preuves d&rsquo;admissibilit\u00e9"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1300px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Vous pouvez consulter les listes des candidats autoris\u00e9s \u00e0 prendre part aux \u00e9preuves d\u2019admissibilit\u00e9 des examens suivants :<\/p>\n<h3>Grade de conseiller des services administratifs (CSAD) &#8211; acc\u00e8s au titre de l&rsquo;ann\u00e9e 2021<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.service-public.pf\/dti\/wp-content\/uploads\/sites\/60\/2022\/09\/Liste-dadmissibilite-CSAD-2021.pdf\" target=\"\" rel=\"noopener\">Liste des candidats autoris\u00e9s \u00e0 participer \u00e0 l&rsquo;\u00e9preuve d&rsquo;admissibilit\u00e9 de l&rsquo;examen professionnel d&rsquo;acc\u00e8s au grade de <strong>conseiller des services administratifs <\/strong>du cadre d&#8217;emplois des attach\u00e9s d&rsquo;administration de la fonction publique de la PF au titre de l&rsquo;ann\u00e9e <strong>2021<\/strong><\/a><\/li>\n<\/ul>\n<h3>Grade d&rsquo;ing\u00e9nieur en chef de 1re cat\u00e9gorie de 2e classe (IN12) &#8211; acc\u00e8s au titre de l&rsquo;ann\u00e9e 2021<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.service-public.pf\/dti\/wp-content\/uploads\/sites\/60\/2022\/09\/Liste-dadmissibilite-IN12-2021.pdf\" target=\"\" rel=\"noopener\">Liste des candidats autoris\u00e9s \u00e0 participer \u00e0 l&rsquo;\u00e9preuve d&rsquo;admissibilit\u00e9 de l&rsquo;examen professionnel d&rsquo;acc\u00e8s au grade d&rsquo;<strong>ing\u00e9nieur en chef de 1re cat\u00e9gorie de 2e classe<\/strong> du cadre d&#8217;emplois des ing\u00e9nieurs de la fonction publique de la PF au titre de l&rsquo;ann\u00e9e <strong>2021<\/strong><\/a><\/li>\n<\/ul>\n<h3>Grade de r\u00e9dacteur chef (REDC) &#8211; acc\u00e8s au titre de l&rsquo;ann\u00e9e 2021<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.service-public.pf\/dti\/wp-content\/uploads\/sites\/60\/2022\/09\/Liste-dadmissibilite-REDC-2021.pdf\" target=\"\" rel=\"noopener\">Liste des candidats autoris\u00e9s \u00e0 participer \u00e0 l&rsquo;\u00e9preuve d&rsquo;admissibilit\u00e9 de l&rsquo;examen professionnel d&rsquo;acc\u00e8s au grade de <strong>r\u00e9dacteur chef<\/strong> du cadre d&#8217;emplois des r\u00e9dacteurs de la fonction publique de la PF au titre de l&rsquo;ann\u00e9e <strong>2021<\/strong><\/a><\/li>\n<\/ul>\n<h3>Grade d&rsquo;aide m\u00e9dico-technique qualifi\u00e9 (AMTQ) &#8211; acc\u00e8s au titre de l&rsquo;ann\u00e9e 2022<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.service-public.pf\/dti\/wp-content\/uploads\/sites\/60\/2022\/09\/Liste-candidats-autorises-epreuves-dadmissibilite-AMTQ-2022.pdf\">Liste des candidats autoris\u00e9s \u00e0 participer aux \u00e9preuves d&rsquo;admissibilit\u00e9 de l&rsquo;examen professionnel pour l&rsquo;acc\u00e8s au grade d&rsquo;<strong>aide m\u00e9dico-technique qualifi\u00e9<\/strong> du cadre d&#8217;emplois des aides m\u00e9dico-techniques de la fonction publique de la PF au titre de l&rsquo;ann\u00e9e <strong>2022<\/strong><\/a><\/li>\n<\/ul>\n<h3>Grade d&rsquo;aide m\u00e9dico-technique principal (AMTP) &#8211; acc\u00e8s au titre de l&rsquo;ann\u00e9e 2022<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.service-public.pf\/dti\/wp-content\/uploads\/sites\/60\/2022\/09\/Liste-candidats-autorises-epreuves-dadmissibilite-AMTP-2022.pdf\">Liste des candidats autoris\u00e9s \u00e0 participer aux \u00e9preuves d&rsquo;admissibilit\u00e9 de l&rsquo;examen professionnel pour l&rsquo;acc\u00e8s au grade d&rsquo;<strong>aide m\u00e9dico-technique principal <\/strong>du cadre d&#8217;emplois des aides m\u00e9dico-techniques de la fonction publique de la PF au titre de l&rsquo;ann\u00e9e <strong>2022<\/strong><\/a><\/li>\n<\/ul>\n<h3>Grade d&rsquo;auxiliaire de soins principal de 2e classe (ASP2) &#8211; acc\u00e8s au titre de l&rsquo;ann\u00e9e 2022<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.service-public.pf\/dti\/wp-content\/uploads\/sites\/60\/2022\/09\/Liste-candidats-autorises-epreuves-dadmissibilite-ASP2-2022.pdf\">Liste des candidats autoris\u00e9s \u00e0 participer \u00e0 l&rsquo;\u00e9preuve d&rsquo;admissibilit\u00e9 de l&rsquo;examen professionnel d&rsquo;acc\u00e8s au grade d&rsquo;<strong>auxiliaire de soins principal de 2e classe<\/strong> du cadre d&#8217;emplois des auxiliaires de soins de la fonction publique de la PF au titre de l&rsquo;ann\u00e9e <strong>2022<\/strong><\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":137,"featured_media":9528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-7765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-examens-professionnels"],"_links":{"self":[{"href":"https:\/\/www.service-public.pf\/dti\/wp-json\/wp\/v2\/posts\/7765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.service-public.pf\/dti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.service-public.pf\/dti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dti\/wp-json\/wp\/v2\/users\/137"}],"replies":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dti\/wp-json\/wp\/v2\/comments?post=7765"}],"version-history":[{"count":0,"href":"https:\/\/www.service-public.pf\/dti\/wp-json\/wp\/v2\/posts\/7765\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.service-public.pf\/dti\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.service-public.pf\/dti\/wp-json\/wp\/v2\/media?parent=7765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.service-public.pf\/dti\/wp-json\/wp\/v2\/categories?post=7765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.service-public.pf\/dti\/wp-json\/wp\/v2\/tags?post=7765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}